{"id":9989,"date":"2021-03-02T00:00:00","date_gmt":"2021-03-02T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/camisas-para-motores-diesel-vantagens-e-utilizacao\/"},"modified":"2026-09-01T09:57:47","modified_gmt":"2026-09-01T09:57:47","slug":"camisas-para-motores-diesel-vantagens-e-utilizacao","status":"publish","type":"post","link":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/","title":{"rendered":"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o"},"content":{"rendered":"<h2>Como preservar o motor:<br \/>\na import\u00e2ncia\u00a0das camisas\u00a0de cilindros<br \/>\npara o sistema de propuls\u00e3o.<\/h2>\n<h4>O funcionamento correto do motor \u00e9 um dos elementos fundamentais para assegurar o desempenho das m\u00e1quinas de movimenta\u00e7\u00e3o de terras tais como escavadoras, miniescavadoras, bulldozers, carregadoras com rodas e dumpers que, devido \u00e0s suas aplica\u00e7\u00f5es, t\u00eam de responder a ritmos de funcionamento elevados.<\/h4>\n<p><span>Uma cuidadosa sele\u00e7\u00e3o e manuten\u00e7\u00e3o dos componentes do motor pode influenciar a longevidade da m\u00e1quina, reduzir os custos de manuten\u00e7\u00e3o e, ao reduzir as <\/span><span>paradas por rupturas<\/span><span>, aumentar a produtividade. Neste&nbsp;artigo, explicamos como e porqu\u00ea as<\/span><span>camisas de motor<\/span><span>, tamb\u00e9m chamadas <\/span><span>liners<\/span><span>, <\/span><span>fornecem uma v\u00e1lida contribui\u00e7\u00e3o<\/span><span>.<\/p>\n<p><\/span><\/p>\n<h3 align=\"left\">Tipos de camisas para cilindros e vantagens da sua utiliza\u00e7\u00e3o<\/p>\n<\/h3>\n<table style=\"float: left;\" align=\"center\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Komatsu-6240-21-2220.jpg\" alt=\"Cylinder liner ITR Komatsu 6240 21 2220\" width=\"152\" height=\"228\"><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Caterpillar-1979322.jpg\" alt=\"Cylinder liner ITR Caterpillar 1979322\" width=\"149\" height=\"223\"><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Caterpillar-1105800.jpg\" alt=\"Cylinder liner ITR Caterpillar 1105800\" width=\"147\" height=\"219\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">As camisas s\u00e3o revestimentos de forma cil\u00edndrica capazes de reter uma fina pel\u00edcula de \u00f3leo na superf\u00edcie da sua parede interior. Quando inseridas no interior dos cilindros do bloco do motor, preservam-no do desgaste causado pelo deslizamento dos pist\u00f5es. Nos blocos de motor das m\u00e1quinas industriais, ao contr\u00e1rio de outras aplica\u00e7\u00f5es menos pesadas, na maioria dos casos recorre-se \u00e0 utiliza\u00e7\u00e3o de cilindros com camisa em vez de fazer trabalhar o pist\u00e3o diretamente em contacto com as paredes do bloco do motor. <\/p>\n<p>Existem <strong>dois tipos principais de camisas<\/strong>: o <strong>primeiro tipo<\/strong> \u00e9 o que n\u00e3o est\u00e1 em contacto direto com a parede do cilindro do bloco. Neste caso, a <strong>camisa \u00e9 revestida pelo fluxo de l\u00edquido refrigerante<\/strong> e por esta raz\u00e3o \u00e9 chamada camisa \u201c<em><strong>lubrificada<\/strong><\/em>\u201d ou \u201c<em><strong>wet<\/strong><\/em>\u201d. O <strong>segundo tipo<\/strong> \u00e9 constitu\u00eddo pelas camisas \u201c<em><strong>a seco<\/strong><\/em>\u201d, tamb\u00e9m chamadas \u201c<em><strong>sleeves<\/strong><\/em>\u201d que s\u00e3o, com efeito, buchas de espessura fina que s\u00e3o instaladas dentro do bloco do motor e cujas paredes <strong>est\u00e3o em contacto direto com o cilindro<\/strong>.<\/p>\n<p>A ado\u00e7\u00e3o de cilindros com camisa por parte dos fabricantes est\u00e1 ligada \u00e0s <strong>vantagens<\/strong> que este sistema traz, sendo as principais as seguintes:<\/p>\n<ul>\n<li><strong>Maior resist\u00eancia<\/strong>. A utiliza\u00e7\u00e3o de camisas separadas do bloco do motor permite utilizar materiais espec\u00edficos com melhor desempenho em compara\u00e7\u00e3o com os utilizados para a constru\u00e7\u00e3o do pr\u00f3prio bloco. As camisas, com efeito, s\u00e3o geralmente realizadas em ligas especiais de ferro fundido com elementos caracterizados por propriedades lubrificantes naturais, como a grafite. Outros elementos como o cr\u00f3mio, van\u00e1dio e molibd\u00e9nio contribuem para uma maior resist\u00eancia \u00e0 corros\u00e3o e ao desgaste devido \u00e0s altas temperaturas.\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Manuten\u00e7\u00e3o mais f\u00e1cil<\/strong>. Quando as camisas est\u00e3o gastas, podem ser substitu\u00eddas mais facilmente do que ter de substituir todo o bloco dos cilindros.\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Maior condutividade t\u00e9rmica<\/strong>. \u00c0 temperatura de funcionamento, as camisas aquecem mais do que os cilindros e devem poder expandir-se tanto diametralmente como longitudinalmente. Se estivessem fundidas com os cilindros, isto conduziria a tens\u00f5es t\u00e9rmicas que provocariam a fratura dos materiais.\n<\/li>\n<li><strong>Menor risco de defeitos<\/strong>. Quanto mais complexa a fus\u00e3o, mais dif\u00edcil \u00e9 produzir superf\u00edcies homog\u00e9neas e com baixas tens\u00f5es residuais.<\/li>\n<\/ul>\n<h3>Que caracter\u00edsticas devem ter as camisas de motor para terem um bom desempenho?<\/h3>\n<p>As camisas est\u00e3o sujeitas a m\u00faltiplas tens\u00f5es:<\/p>\n<ul>\n<li>mec\u00e2nicas, causadas pela press\u00e3o de combust\u00e3o;<\/li>\n<li>t\u00e9rmicas, causadas pela elevada temperatura resultante do processo de combust\u00e3o;<\/li>\n<li>de desgaste, causadas principalmente por tr\u00eas fatores:\n<ul>\n<li>abras\u00e3o, que depende da efici\u00eancia do filtro de ar e de \u00f3leo,<\/li>\n<li>corros\u00e3o, devido aos materiais produzidos pela combust\u00e3o,<\/li>\n<li>atrito ou fric\u00e7\u00e3o, causado por falta de lubrifica\u00e7\u00e3o.\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Por todas estas raz\u00f5es, o processo de fabrica\u00e7\u00e3o destes componentes \u00e9 muito importante e o seu design deve satisfazer caracter\u00edsticas precisas para preservar o motor e prolongar o seu ciclo de vida, tais como:<\/p>\n<ul>\n<li><strong>elevadas propriedades anticorrosivas e de resist\u00eancia,<\/strong><\/li>\n<li><strong>baixo atrito,<\/strong><\/li>\n<li><strong>alta precis\u00e3o.\n<p><\/strong><\/li>\n<\/ul>\n<p>Para reduzir o atrito e, desta forma, prolongar a vida \u00fatil do motor, uma caracter\u00edstica fundamental das camisas s\u00e3o os sulcos cruzados na parede. Os sulcos da superf\u00edcie servem para manter uma quantidade suficiente de \u00f3leo nas paredes internas da camisa, mantendo uma <strong>lubrifica\u00e7\u00e3o adequada no contacto das faixas com a camisa<\/strong>. Geralmente, estima-se que o<strong> \u00e2ngulo de interse\u00e7\u00e3o correto para os sulcos<\/strong> <strong>das paredes<\/strong> \u00e9 de cerca de <strong>45\u00b0<\/strong>, uma vez que isto favorece uma <strong>lubrifica\u00e7\u00e3o homog\u00e9nea<\/strong> e, portanto, uma <strong>maior durabilidade das superf\u00edcies<\/strong>, no entanto, podem ser encontradas solu\u00e7\u00f5es com \u00e2ngulos diferentes, dependendo dos materiais e do tipo de utiliza\u00e7\u00e3o.<\/p>\n<p><span>Por fim, entre os elementos que contribuem para aumentar a resist\u00eancia e reduzir o desgaste das superf\u00edcies das camisas incluem-se, respetivamente, o rolamento da flange e o revestimento anticorrosivo na parede externa.<br \/><\/span><\/p>\n<h3>Como instalar corretamente as camisas dentro dos cilindros?<\/h3>\n<p>Segue-se uma lista dos principais passos e algumas precau\u00e7\u00f5es ou cuidados para a correta instala\u00e7\u00e3o das camisas no interior dos cilindros, para evitar falhas e um desgaste prematuro.<\/p>\n<ol>\n<li>Limpar bem o bloco dos cilindros: a sujidade acumulada pode causar a ruptura da flange.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-1.jpg\" alt=\"Cylinder liner ITR Usco 1\" width=\"582\" height=\"388\"><\/p>\n<\/li>\n<li>Verificar se n\u00e3o existem rebarbas ou materiais salientes e, se necess\u00e1rio, remov\u00ea-los para evitar problemas com os vedantes.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-3.jpg\" alt=\"Cylinder liner ITR Usco 3\" width=\"584\" height=\"328\"><\/p>\n<\/li>\n<li>Inserir as camisas no bloco dos cilindros sem vedantes ou outros enchimentos e verificar a protuber\u00e2ncia correta da flange, rodando-a se necess\u00e1rio at\u00e9 encontrar a configura\u00e7\u00e3o correta.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-4.jpg\" alt=\"Cylinder liner ITR Usco 4\" width=\"585\" height=\"390\"><\/p>\n<\/li>\n<li>Quando a posi\u00e7\u00e3o da camisa estiver correta, remov\u00ea-la depois de colocar uma marca de alinhamento tanto na camisa como no bloco dos cilindros, para que possa ser reinserida na mesma posi\u00e7\u00e3o.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-5.jpg\" alt=\"Cylinder liner ITR Usco 5\" width=\"587\" height=\"391\"><\/p>\n<\/li>\n<li>Inserir os vedantes evitando poss\u00edveis tor\u00e7\u00f5es, pois podem causar distor\u00e7\u00e3o da camisa, gerar fric\u00e7\u00e3o contra a mesma, ou reduzir a folga entre o pist\u00e3o e a camisa.<br \/>Muitos instaladores acreditam que, para facilitar o processo, os vedantes devem ser lubrificados ou ensaboados antes da instala\u00e7\u00e3o. Em vez disso, o m\u00e9todo correto \u00e9 instalar o vedante &#8220;a seco&#8221;, inserindo uma haste redonda como uma chave de fendas e movendo-a ao redor de toda a circunfer\u00eancia do vedante para aderir uniformemente. S\u00f3 depois se devem lubrificar os v\u00e1rios componentes.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-6.jpg\" alt=\"Cylinder liner ITR Usco 6\" width=\"588\" height=\"392\"><\/p>\n<\/li>\n<li>Mergulhar o vedante em \u00f3leo SAE 30 limpo. Instal\u00e1-lo sobre a camisa que dever\u00e1 ser inserida imediatamente no bloco dos cilindros, antes que o vedante se expanda.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-7.jpg\" alt=\"Cylinder liner ITR Usco 7\" width=\"591\" height=\"623\"><\/p>\n<\/li>\n<li>Assegurar que a marca anteriormente feita na camisa esteja alinhada com a marca no bloco. Utilizar a ferramenta especial para empurrar a camisa para a sua posi\u00e7\u00e3o.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-8.jpg\" alt=\"Cylinder liner ITR Usco 8\" width=\"592\" height=\"394\"><\/p>\n<\/li>\n<li>Repetir os passos para todas as camisas dispon\u00edveis.<\/li>\n<\/ol>\n<h3 align=\"left\">Camisas para cilindros ITR<\/h3>\n<p align=\"left\">A escolha e utiliza\u00e7\u00e3o adequada de apenas um pequeno componente podem fazer toda a diferen\u00e7a no desempenho e ciclo de vida das m\u00e1quinas de movimenta\u00e7\u00e3o de terras. Por este motivo, \u00e9 igualmente importante contar com um parceiro especializado.&nbsp;<strong>A ITR Usco tem uma vasta gama de camisas<\/strong>, com di\u00e2metros que v\u00e3o de 94 mm a 170 mm, para <strong>Caterpillar<strong>\u00ae<\/strong>, Komatsu<strong>\u00ae<\/strong>, Volvo<strong>\u00ae<\/strong>, Hitachi<strong>\u00ae<\/strong> e JCB<strong>\u00ae<\/strong><\/strong>.&nbsp;<a href=\"\/pt\/contactos\/\" target=\"_blank\"><strong>Contacte a nossa equipa<\/strong><\/a> para mais informa\u00e7\u00f5es sobre os tipos e materiais mais adequados \u00e0s suas aplica\u00e7\u00f5es.<\/p>\n<p><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como preservar o motor:<br \/>\na import\u00e2ncia\u00a0das camisas\u00a0de cilindros<br \/>\npara o sistema de propuls\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":5104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[152,100],"tags":[],"class_list":["post-9989","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pecas-de-reposicao","category-revista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"Como preservar o motor: a import\u00e2ncia\u00a0das camisas\u00a0de cilindros para o sistema de propuls\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-02T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o\",\"datePublished\":\"2021-03-02T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/\"},\"wordCount\":1195,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"articleSection\":[\"Pe\u00e7as de reposi\u00e7\u00e3o\",\"Revista\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/\",\"name\":\"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"datePublished\":\"2021-03-02T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:57:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/camisas-para-motores-diesel-vantagens-e-utilizacao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/","og_locale":"pt_PT","og_type":"article","og_title":"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o - ITR WORLD","og_description":"Como preservar o motor: a import\u00e2ncia\u00a0das camisas\u00a0de cilindros para o sistema de propuls\u00e3o.","og_url":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2021-03-02T00:00:00+00:00","article_modified_time":"2026-09-01T09:57:47+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assistenza@intersezione.com","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o","datePublished":"2021-03-02T00:00:00+00:00","dateModified":"2026-09-01T09:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/"},"wordCount":1195,"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","articleSection":["Pe\u00e7as de reposi\u00e7\u00e3o","Revista"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/","url":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/","name":"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","datePublished":"2021-03-02T00:00:00+00:00","dateModified":"2026-09-01T09:57:47+00:00","author":{"@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/pt-pt\/camisas-para-motores-diesel-vantagens-e-utilizacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Camisas para motores Diesel: vantagens e utiliza\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/pt-pt\/#website","url":"https:\/\/itrworld.com\/pt-pt\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/pt-pt\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=9989"}],"version-history":[{"count":1,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9989\/revisions"}],"predecessor-version":[{"id":9991,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9989\/revisions\/9991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media\/5104"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=9989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=9989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=9989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}