{"id":9973,"date":"2021-05-11T00:00:00","date_gmt":"2021-05-11T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/como-evitar-o-desgaste-do-material-rodante-parte-1\/"},"modified":"2026-09-01T09:57:05","modified_gmt":"2026-09-01T09:57:05","slug":"como-evitar-o-desgaste-do-material-rodante-parte-1","status":"publish","type":"post","link":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/","title":{"rendered":"Como evitar o desgaste do material rodante [Parte 1]"},"content":{"rendered":"<h2>Os 7 erros a serem evitados no uso de m\u00e1quinas de esteiras que aceleram o desgaste do material rodante.<\/h2>\n<h4>Os custos associados ao material rodante representam uma alta porcentagem do custo total de opera\u00e7\u00e3o da m\u00e1quina de esteiras. O impacto nos custos de manuten\u00e7\u00e3o durante a vida total da m\u00e1quina pode atingir 50% dos custos totais.<\/h4>\n<p>Isto porque, durante seu uso, o <strong>material rodante est\u00e1 sujeito a tens\u00f5es e agentes externos<\/strong> que, com o tempo, levam ao desgaste de seus componentes. Um material rodante que n\u00e3o est\u00e1 funcionando bem n\u00e3o s\u00f3 reduz a efici\u00eancia do ve\u00edculo, mas tamb\u00e9m pode danificar outras pe\u00e7as, afetando seriamente a produtividade e os custos.<br \/>Como qualquer outro componente essencial, o material rodante requer, portanto, a devida <strong>aten\u00e7\u00e3o e boas pr\u00e1ticas<\/strong> para prolongar sua vida \u00fatil, diminuindo o desgaste e permitindo uma economia consider\u00e1vel em termos de custos de manuten\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<h3>Como podemos definir o desgaste e quais s\u00e3o os principais fatores que o influenciam?<\/h3>\n<p>H\u00e1 muitas defini\u00e7\u00f5es para este fen\u00f4meno. A <em>American Society for Testing and Materials<\/em> (ASTM) define o <strong>desgaste<\/strong> como <strong>uma perda mec\u00e2nica de material que ocorre devido ao contato entre duas superf\u00edcies<\/strong>. Geralmente, e a t\u00edtulo de exemplo, podemos falar de:<\/p>\n<ul>\n<li><strong>Desgaste por ades\u00e3o<\/strong>, originada pela intera\u00e7\u00e3o de rugosidade entre duas superf\u00edcies em contato com uma for\u00e7a de ades\u00e3o consistente.<\/li>\n<li><strong>Desgaste por abras\u00e3o<\/strong>, que ocorre quando part\u00edculas externas ou que pertencem a uma superf\u00edcie \u00e1spera e dura deslizam atrav\u00e9s de uma superf\u00edcie relativamente macia.<\/li>\n<li><strong>Desgaste por fadiga<\/strong>, com a forma\u00e7\u00e3o de rachaduras e vazios em superf\u00edcies s\u00f3lidas, amplificadas por carga cont\u00ednua e vari\u00e1vel.<\/li>\n<li><strong>Fretting<\/strong>, causado por fric\u00e7\u00e3o constante e c\u00edclica de pequena amplitude entre duas superf\u00edcies.<\/li>\n<li><strong>Desgaste por eros\u00e3o<\/strong>, produzido por um movimento deslizante de part\u00edculas ou fluidos sobre superf\u00edcies a uma velocidade muito elevada.<\/li>\n<li><strong>Corros\u00e3o por desgaste e por oxida\u00e7\u00e3o<\/strong>, que ocorre como efeito combinado da a\u00e7\u00e3o qu\u00edmica e mec\u00e2nica.\n<\/li>\n<\/ul>\n<p>O <strong>desgaste<\/strong>, no material rodante, \u00e9 causado principalmente pelos dois primeiros desses mecanismos, e <strong>pode ser agravado por tr\u00eas fatores principais<\/strong> que, felizmente, conseguimos administrar e controlar, que s\u00e3o:<\/p>\n<ul>\n<li><strong>H\u00e1bitos incorretos<\/strong> no uso da m\u00e1quina, especialmente a <strong>velocidade<\/strong><\/li>\n<li><strong>Carga<\/strong><\/li>\n<li>Presen\u00e7a de <strong>materiais abrasivos externos\n<p><\/strong><\/li>\n<\/ul>\n<p>Neste artigo analisamos o primeiro fator, ou seja, os h\u00e1bitos incorretos dos operadores ao utilizar a m\u00e1quina, especialmente em rela\u00e7\u00e3o \u00e0 velocidade, embora a carga desempenhe um papel igualmente importante nesses h\u00e1bitos.<\/p>\n<h3>7 erros comuns a serem evitados ao usar a m\u00e1quina para reduzir o desgaste do material rodante.<\/h3>\n<p>A longo prazo, os componentes do material rodante em m\u00e1quinas com esteiras de a\u00e7o ou borracha ir\u00e3o se desgastar. Todavia, existem maneiras de <strong>limitar esse processo<\/strong> inevit\u00e1vel, como um gerenciamento correto no dia a dia da m\u00e1quina e do material rodante. A <strong>melhoria da t\u00e9cnica operacional<\/strong> permitir\u00e1 <strong>evitar os h\u00e1bitos incorretos<\/strong> que causam rupturas, custos extras e quedas na produtividade. Aqui est\u00e3o os 7 erros mais comuns no uso de m\u00e1quinas que devem ser corrigidos para conseguir com o material rodante que dure mais tempo, retardando o processo de desgaste, que \u00e9 inevit\u00e1vel.<\/p>\n<h4>Erros t\u00edpicos cometidos em rela\u00e7\u00e3o a todos os tipos de m\u00e1quinas<\/p>\n<\/h4>\n<p><strong>1. Elevada velocidade de avan\u00e7o e marcha a r\u00e9<\/p>\n<p><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/BbPc0nBSgiY\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p><strong><br \/><\/strong>Por vezes pode ser \u00fatil trabalhar em alta velocidade, mas este h\u00e1bito acelera o desgaste do material rodante e de suas pe\u00e7as, tais como elos, buchas, roletes e rodas-guia e motrizes. Geralmente, <strong>\u00e9 prefer\u00edvel trabalhar com plena carga mantendo uma baixa velocidade do que trabalhar a meia carga com uma velocidade superior.<\/strong> Embora possa n\u00e3o parecer, a primeira solu\u00e7\u00e3o permite fazer o trabalho mais rapidamente, economiza combust\u00edvel e evita o desgaste prematuro do material rodante. Tamb\u00e9m pode ser arriscado trabalhar em marcha \u00e0 r\u00e9, seja em alta ou baixa velocidade. Em particular, a invers\u00e3o acelera o desgaste das buchas e da roda motriz. Portanto, \u00e9 aconselh\u00e1vel limitar o uso de marcha r\u00e9 para quando estritamente necess\u00e1rio, somente para curtas dist\u00e2ncias e sem nunca acelerar demais.<\/p>\n<p><strong>2. Movimentos desnecess\u00e1rios<\/p>\n<p><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/E4eshkRdOeA\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p><strong>&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <br \/>Alguns operadores tendem a utilizar o ve\u00edculo de esteiras tamb\u00e9m fora da \u00e1rea de trabalho, por exemplo, durante o intervalo do almo\u00e7o. Isso faz com que o material rodante se desgaste mais rapidamente, em detrimento da produtividade, afetando o consumo de combust\u00edvel. <strong>Para desloca\u00e7\u00f5es n\u00e3o inerentes \u00e0 opera\u00e7\u00e3o, \u00e9 recomend\u00e1vel utilizar outros ve\u00edculos mais apropriados<\/strong>.<\/p>\n<p><strong>3. Mudan\u00e7as r\u00e1pidas de dire\u00e7\u00e3o<\/p>\n<p><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/JSF1P2YvZac\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p><strong><br \/><\/strong>A contra rota\u00e7\u00e3o de uma m\u00e1quina com material rodante acelera o desgaste de seus componentes e gera cargas elevadas e n\u00e3o produtivas que agravam o fen\u00f4meno. Portanto, \u00e9 melhor n\u00e3o utilizar esta t\u00e9cnica a menos que as condi\u00e7\u00f5es de trabalho o exijam: geralmente, nunca s\u00e3o realmente necess\u00e1rias mudan\u00e7as de dire\u00e7\u00e3o bruscas. <strong>A melhor solu\u00e7\u00e3o \u00e9 girar a m\u00e1quina gradualmente<\/strong> enquanto avan\u00e7a lentamente para frente ou em marcha \u00e0 r\u00e9. As voltas graduais s\u00e3o mais f\u00e1ceis de executar, minimizam os solavancos e o desgaste do material rodante, limitando os danos causados por poss\u00edveis falhas das pe\u00e7as envolvidas.<\/p>\n<p><strong>4. Girar sempre para o mesmo lado<\/p>\n<p><\/strong><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/OVRQqwI5Qy8\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p>O desgaste do ve\u00edculo \u00e9 inevit\u00e1vel, mas para mant\u00ea-lo uniforme, \u00e9 preciso prestar aten\u00e7\u00e3o \u00e0 maneira como gira seu ve\u00edculo. Se girar sempre na mesma dire\u00e7\u00e3o, os componentes do material rodante desse lado se desgastar\u00e3o mais cedo do que os do outro lado. Por exemplo, se girar mais vezes para a esquerda, o lado direito se desgastar\u00e1 mais cedo. Sempre que poss\u00edvel, posicionar o ve\u00edculo de modo que possa <strong>girar em outra dire\u00e7\u00e3o de vez em quando<\/strong>.<\/p>\n<h4>Erros t\u00edpicos cometidos em rela\u00e7\u00e3o aos tratores de esteira<\/p>\n<\/h4>\n<p><strong>5. Uso incorreto da l\u00e2mina do trator de esteira<\/p>\n<p><\/strong><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/zKB9wgU09us\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p>Para mover um trator de esteira totalmente carregado de maneira eficaz, \u00e9 necess\u00e1rio prestar aten\u00e7\u00e3o \u00e0 posi\u00e7\u00e3o da l\u00e2mina do ve\u00edculo durante o movimento. Se a l\u00e2mina estiver muito inclinada para baixo, mant\u00e9m a posi\u00e7\u00e3o de escava\u00e7\u00e3o mesmo quando n\u00e3o \u00e9 mais necess\u00e1ria. A posi\u00e7\u00e3o errada faz com que a m\u00e1quina avance com dificuldade e com um gasto consider\u00e1vel de energia para pouca efic\u00e1cia, gera uma carga excessiva e corre o risco de danificar a l\u00e2mina. Por sua vez, o material rodante est\u00e1 sujeito a um deslizamento que gera um desgaste que n\u00e3o \u00e9 compensado pelo aumento da produtividade e, a longo prazo, danifica seus componentes. Em vez disso, <strong>o sistema mais eficaz \u00e9 escavar, encher a l\u00e2mina do trator de esteira com uma carga completa e depois levant\u00e1-la do ch\u00e3o<\/strong> para que a m\u00e1quina opere da maneira mais funcional poss\u00edvel.<\/p>\n<p><strong>6. Inclina\u00e7\u00e3o incorreta do ripper<\/p>\n<p><\/strong><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/yMit3HS_gac\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p>O fen\u00f4meno do deslizamento ocorre tamb\u00e9m durante o ripping. Quando o ripper come\u00e7a a penetrar no solo, a parte traseira da m\u00e1quina \u00e9 levantada, criando um desequil\u00edbrio. Manter esta inclina\u00e7\u00e3o \u00e9 um h\u00e1bito incorreto que faz com que os componentes na frente da m\u00e1quina trabalhem em esfor\u00e7o, incluindo a parte dianteira do material rodante. <strong>Depois de penetrar o solo, o ripper deve ser inclinado na posi\u00e7\u00e3o de trabalho<\/strong> para distribuir o peso uniformemente, mover a m\u00e1quina para frente corretamente e preservar o material rodante por mais tempo.<\/p>\n<h4>Erro t\u00edpico cometido com escavadeiras<\/p>\n<\/h4>\n<p><strong>7. Avan\u00e7ar no lado da roda motriz<\/p>\n<p><\/strong><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/sZK83zuQkd8\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p>Para o correto avan\u00e7o da m\u00e1quina, <strong>o pinh\u00e3o do material rodante deve permanecer sempre na parte traseira<\/strong>. Devem ser evitadas situa\u00e7\u00f5es em que a escavadeira \u00e9 movida para frente com a cabine virada para o lado do pinh\u00e3o. Com essa posi\u00e7\u00e3o incorreta, embora a escavadeira avance, a parte do material rodante est\u00e1 em modo marcha a r\u00e9, esfor\u00e7ando inutilmente seus componentes. De fato, \u00e9 aconselh\u00e1vel limitar o m\u00e1ximo poss\u00edvel a dura\u00e7\u00e3o da marcha a r\u00e9, pois esse mecanismo acelera o desgaste do material rodante, implicando custos de manuten\u00e7\u00e3o mais altos.<\/p>\n<p>Na pr\u00f3xima edi\u00e7\u00e3o falaremos em detalhe das outras duas causas, ou seja, a carga e a presen\u00e7a de materiais abrasivos externos, que t\u00eam um impacto mais espec\u00edfico no desgaste do material rodante.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os 7 erros a serem evitados no uso de m\u00e1quinas de esteiras que aceleram o desgaste do material rodante.<\/p>\n","protected":false},"author":1,"featured_media":5082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[167,100],"tags":[],"class_list":["post-9973","post","type-post","status-publish","format-standard","has-post-thumbnail","category-material-rodante","category-revista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como evitar o desgaste do material rodante [Parte 1] - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como evitar o desgaste do material rodante [Parte 1] - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"Os 7 erros a serem evitados no uso de m\u00e1quinas de esteiras que aceleram o desgaste do material rodante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-11T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:57:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Undercarriage-Wear.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"Como evitar o desgaste do material rodante [Parte 1]\",\"datePublished\":\"2021-05-11T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:57:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/\"},\"wordCount\":1430,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Undercarriage-Wear.jpg\",\"articleSection\":[\"Material rodante\",\"Revista\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/\",\"name\":\"Como evitar o desgaste do material rodante [Parte 1] - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Undercarriage-Wear.jpg\",\"datePublished\":\"2021-05-11T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:57:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Undercarriage-Wear.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Undercarriage-Wear.jpg\",\"width\":1600,\"height\":867},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-evitar-o-desgaste-do-material-rodante-parte-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como evitar o desgaste do material rodante [Parte 1]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como evitar o desgaste do material rodante [Parte 1] - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/","og_locale":"pt_PT","og_type":"article","og_title":"Como evitar o desgaste do material rodante [Parte 1] - ITR WORLD","og_description":"Os 7 erros a serem evitados no uso de m\u00e1quinas de esteiras que aceleram o desgaste do material rodante.","og_url":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2021-05-11T00:00:00+00:00","article_modified_time":"2026-09-01T09:57:05+00:00","og_image":[{"width":1600,"height":867,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Undercarriage-Wear.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assistenza@intersezione.com","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"Como evitar o desgaste do material rodante [Parte 1]","datePublished":"2021-05-11T00:00:00+00:00","dateModified":"2026-09-01T09:57:05+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/"},"wordCount":1430,"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Undercarriage-Wear.jpg","articleSection":["Material rodante","Revista"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/","url":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/","name":"Como evitar o desgaste do material rodante [Parte 1] - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Undercarriage-Wear.jpg","datePublished":"2021-05-11T00:00:00+00:00","dateModified":"2026-09-01T09:57:05+00:00","author":{"@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Undercarriage-Wear.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Undercarriage-Wear.jpg","width":1600,"height":867},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/pt-pt\/como-evitar-o-desgaste-do-material-rodante-parte-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Como evitar o desgaste do material rodante [Parte 1]"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/pt-pt\/#website","url":"https:\/\/itrworld.com\/pt-pt\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/pt-pt\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=9973"}],"version-history":[{"count":0,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media\/5082"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=9973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=9973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=9973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}