{"id":9877,"date":"2023-10-18T00:00:00","date_gmt":"2023-10-18T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/como-medir-e-substituir-as-esteiras-de-borracha\/"},"modified":"2026-09-01T09:56:36","modified_gmt":"2026-09-01T09:56:36","slug":"como-medir-e-substituir-as-esteiras-de-borracha","status":"publish","type":"post","link":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/","title":{"rendered":"Como medir e substituir as esteiras de borracha"},"content":{"rendered":"<h2>No setor das m\u00e1quinas de movimenta\u00e7\u00e3o de terras, as esteiras de borracha devem ser substitu\u00eddas quando est\u00e3o gastas ou danificadas, escolhendo as mais adequadas para cada tipo de m\u00e1quina e aplica\u00e7\u00e3o.<\/h2>\n<h4>Desde a medi\u00e7\u00e3o correta das esteiras de borracha, at\u00e9 as aplica\u00e7\u00f5es para as quais s\u00e3o usadas, dependendo da m\u00e1quina, h\u00e1 muitos fatores a serem considerados para efetuar uma substitui\u00e7\u00e3o correta.<\/h4>\n<p dir=\"ltr\"><span>Como qualquer outro elemento do material rodante, tamb\u00e9m as <\/span><strong>esteiras de borracha<\/strong><span> sofrem desgaste ou podem ficar danificadas com o tempo e o uso. <\/span><span>Para que a m\u00e1quina de movimenta\u00e7\u00e3o de terras continue <\/span><strong>trabalhando de forma eficiente<\/strong><span>, sem sobrecarregar os outros componentes e aumentar os custos de manuten\u00e7\u00e3o, \u00e9 necess\u00e1rio substitu\u00ed-las.<\/span><span><br \/><\/span><span><br \/><\/span><span>No v\u00eddeo, mostramos-lhe os passos para executar, de forma r\u00e1pida e segura, o procedimento de substitui\u00e7\u00e3o das esteiras de borracha.&nbsp;<\/p>\n<p><\/span><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/MXEpsVmGgyw?si=szXVerwDEKUUWt0r\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p dir=\"ltr\"><span><br \/><\/span><span>Ter o <\/span><span>tamanho correto <\/span><span>das esteiras de borracha permite encontrar a substitui\u00e7\u00e3o perfeita. Por vezes, a medida est\u00e1 impressa na parte interna da esteira que precisa ser substitu\u00edda, mas pode acontecer que os n\u00fameros sejam pouco leg\u00edveis ou n\u00e3o sejam leg\u00edveis de todo.<\/span><span><br \/><\/span><span><br \/><\/span><span>Por isso, para garantir a seguran\u00e7a, \u00e9 \u00fatil saber <strong>como <\/strong><\/span><strong>medir corretamente as esteiras de borracha<\/strong><span> e, assim, poder efetuar uma substitui\u00e7\u00e3o correta. <br \/>Os <\/span><strong>tr\u00eas valores <\/strong><span>necess\u00e1rios para definir o tamanho correto s\u00e3o:<\/span><\/p>\n<ol>\n<li>\n<p dir=\"ltr\"><span>A <\/span><strong>largura da esteira<\/strong><span> (em mil\u00edmetros): por exemplo, 180 mm<\/span><\/p>\n<\/li>\n<li>\n<p dir=\"ltr\"><span>A <strong>dist\u00e2ncia longitudinal<\/strong><\/span><span>, em mil\u00edmetros, <\/span><strong>entre os elementos internos de tra\u00e7\u00e3o <\/strong><span>(inser\u00e7\u00f5es de metal ou almofadas de borracha)<\/span><span>: <\/span><span>por exemplo, 60 mm<\/span><\/p>\n<\/li>\n<li>\n<p dir=\"ltr\"><span>O <\/span><strong>n\u00famero de dentes no interior da esteira<\/strong><span>: por exemplo, 37<\/span><\/p>\n<\/li>\n<\/ol>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"assets\/Uploads\/_resampled\/ResizedImageWzYwMCw0Mjld\/misurazione-cingoli-in-gomma-PT-BR.jpg\" alt=\"misurazione cingoli in gomma PT BR\" width=\"600\" height=\"429\"><\/p>\n<p dir=\"ltr\"><span>Considerando os valores apresentados como exemplo, neste caso o tamanho da esteira de borracha ser\u00e1 o seguinte: <\/span><span>180x60x37<\/span><span>.<\/p>\n<p><\/span><\/p>\n<h3 dir=\"ltr\"><span>Quando as esteiras de borracha devem ser substitu\u00eddas?<\/span><\/h3>\n<p dir=\"ltr\"><span>As esteiras de borracha devem ser substitu\u00eddas quando atingem seu <\/span><strong>fim de vida normal<\/strong><span>. Se o rasto ou o piso da esteira estiverem gastos, n\u00e3o proporcionam <\/span><strong>ader\u00eancia <\/strong><span>suficiente entre a m\u00e1quina e o solo. <\/span><span><br \/><\/span><span><br \/><\/span><span>As lagartas de borracha tamb\u00e9m podem ser <\/span><strong>danificadas prematuramente<\/strong><span>, por exemplo, pela <\/span><strong>ruptura <\/strong><span>de cabos ou de cordas de a\u00e7o internas, pelo desprendimento ou descama\u00e7\u00e3o do rasto ou piso e pelo <\/span><strong>desprendimento <\/strong><span>de inser\u00e7\u00f5es met\u00e1licas internas.<\/span><span><br \/><\/span><span><br \/><\/span><span>A esse respeito, relembramos que existem <\/span><strong>boas pr\u00e1ticas<\/strong><span> para manter as esteiras em boas condi\u00e7\u00f5es durante o m\u00e1ximo de tempo poss\u00edvel. Essas pr\u00e1ticas incluem: <strong>inspe\u00e7\u00f5es visuais regulares<\/strong>, <\/span><strong>limpeza <\/strong><span><strong>regular,<\/strong> <strong>ajuste da tens\u00e3o<\/strong>, armazenamento adequado, <\/span><span><strong>manuten\u00e7\u00e3o<\/strong> <\/span><span><strong>regular<\/strong> e lubrifica\u00e7\u00e3o de outros componentes do material rodante.<\/p>\n<p><\/span><\/p>\n<h2 dir=\"ltr\"><span>Os tipos de esteiras de borracha<\/span><\/h2>\n<p dir=\"ltr\"><span>Quando chegar o momento da substitui\u00e7\u00e3o, deve-se ter em mente que os equipamentos de constru\u00e7\u00e3o n\u00e3o s\u00e3o todos iguais. H\u00e1 <\/span><strong>diferentes tipos de esteiras de borracha<\/strong><span> cuja conce\u00e7\u00e3o \u00e9 mais adequada ao tamanho e \u00e0 pot\u00eancia da m\u00e1quina, mas tamb\u00e9m a uma ou outra das tarefas a que se destina.&nbsp;<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Elementos como a composi\u00e7\u00e3o da <\/span><strong>mistura <\/strong><span>de borracha, <\/span><span>a<\/span><span>presen\u00e7a ou aus\u00eancia de <\/span><strong>n\u00facleo met\u00e1lico<\/strong><span>, a <\/span><span>forma da guia do rolete ou a diferente tipologia do piso resultam em<\/span><span>esteiras de borracha com diferentes <\/span><strong>desempenhos <\/strong><span>e projetadas especificamente para diferentes usos<\/span><span>.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Para sua <\/span><strong>substitui\u00e7\u00e3o<\/strong><span>, al\u00e9m de ter o tamanho correto, \u00e9 necess\u00e1rio usar esteiras de borracha mais adequadas e de alto desempenho, dependendo da m\u00e1quina e do trabalho que ela ter\u00e1 de fazer. Apresentamos a seguir os principais tipos de esteiras de borracha ITR.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha convencionais<\/strong><\/p>\n<p dir=\"ltr\"><span>As esteiras de borracha convencionais s\u00e3o concebidas de modo que os roletes n\u00e3o entrem em contato com as guias de metal. Devido \u00e0 sua conce\u00e7\u00e3o, elas s\u00f3 podem ser usadas em material rodante concebido para uso <\/span><span>exclusivo <\/span><span>de esteiras de borracha, e n\u00e3o de a\u00e7o.&nbsp;<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha intercambi\u00e1veis<\/strong><\/p>\n<p dir=\"ltr\"><span>Ao contr\u00e1rio das esteiras de borracha convencionais, as esteiras de borracha intercambi\u00e1veis podem ser usadas em <\/span><span>esteiras <\/span><span>concebidas para o uso de esteiras de borracha e de a\u00e7o. Para esse tipo de esteira, os roletes funcionam da mesma forma que para as esteiras de a\u00e7o.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha com n\u00facleo n\u00e3o met\u00e1lico (NMC)<\/strong><\/p>\n<p dir=\"ltr\"><span>As esteiras de borracha NMC t\u00eam uma estrutura muito leve e flex\u00edvel. Essas vantagens s\u00e3o proporcionadas por sua composi\u00e7\u00e3o especial de <\/span><span>composto de borracha e cabos internos <\/span><span>para usos exigentes. Al\u00e9m disso, a largura da esteira e o desenho do piso conferem maior capacidade de tra\u00e7\u00e3o e flutua\u00e7\u00e3o.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha para manuten\u00e7\u00e3o de \u00e1reas verdes<\/strong><\/p>\n<p dir=\"ltr\"><span>As esteiras de borracha para a manuten\u00e7\u00e3o de \u00e1reas verdes podem ter <\/span><span>diferentes pisos<\/span><span>, mais agressivos ou delicados, dependendo das circunst\u00e2ncias, como a necessidade de lidar com fortes declives ou respeitar o gramado.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha para m\u00e1quinas agr\u00edcolas<\/strong><\/p>\n<p dir=\"ltr\"><span>As esteiras de borracha especialmente projetadas para m\u00e1quinas agr\u00edcolas oferecem uma <\/span><span>resist\u00eancia e elasticidade<\/span><span> consider\u00e1veis, bem como uma elevada capacidade de tra\u00e7\u00e3o com menor compacta\u00e7\u00e3o do solo. Elas s\u00e3o adequadas para uma <\/span><span>variedade de aplica\u00e7\u00f5es<\/span><span>, tanto para m\u00e1quinas grandes e potentes quanto para m\u00e1quinas menores em vinhedos ou pomares que exigem estabilidade e respeito pelo solo.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha antivibra\u00e7\u00e3o (AV)<\/strong><\/p>\n<p dir=\"ltr\"><span>As esteiras de borracha antivibra\u00e7\u00e3o apresentam um n\u00facleo de metal e uma guia projetados para diminuir as vibra\u00e7\u00f5es e o peso da esteira. Gra\u00e7as ao design da <\/span><span>guia em forma de diamante<\/span><span>, os rolos deslizam de forma mais est\u00e1vel. Esses, movendo-se em uma superf\u00edcie alternada, conseguem reduzir o ru\u00eddo do ve\u00edculo e at\u00e9 75% de suas vibra\u00e7\u00f5es.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Esteiras de borracha antimarcas<\/strong><\/p>\n<p dir=\"ltr\"><span>Por fim, as esteiras de borracha antimarcas s\u00e3o a escolha ideal para trabalhos em que \u00e9 necess\u00e1rio <\/span><span>manter o pavimento intacto<\/span><span> sem deixar vest\u00edgios (por exemplo, em centros hist\u00f3ricos ou no interior de edif\u00edcios industriais). Gra\u00e7as a um composto especial, elas garantem a preserva\u00e7\u00e3o ideal da superf\u00edcie de apoio.<\/p>\n<p><\/span><\/p>\n<h3><span id=\"docs-internal-guid-dfb27592-7fff-b795-fcf6-8e8f3706d879\"><span>Deseja saber mais sobre as esteiras de borracha da ITR USCO e como substitu\u00ed-las?<\/span><\/span><\/h3>\n<p><span id=\"docs-internal-guid-dfb27592-7fff-b795-fcf6-8e8f3706d879\"><span>Entre em contato conosco preenchendo o formul\u00e1rio abaixo e entraremos em conta com todas as informa\u00e7\u00f5es de que necessita.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No setor das m\u00e1quinas de movimenta\u00e7\u00e3o de terras, as esteiras de borracha devem ser substitu\u00eddas quando est\u00e3o gastas ou danificadas, escolhendo as mais adequadas para cada tipo de m\u00e1quina e aplica\u00e7\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":4965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[167,100],"tags":[],"class_list":["post-9877","post","type-post","status-publish","format-standard","has-post-thumbnail","category-material-rodante","category-revista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como medir e substituir as esteiras de borracha - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como medir e substituir as esteiras de borracha - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"No setor das m\u00e1quinas de movimenta\u00e7\u00e3o de terras, as esteiras de borracha devem ser substitu\u00eddas quando est\u00e3o gastas ou danificadas, escolhendo as mais adequadas para cada tipo de m\u00e1quina e aplica\u00e7\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-18T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Rubber-Tracks-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"Como medir e substituir as esteiras de borracha\",\"datePublished\":\"2023-10-18T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/\"},\"wordCount\":1066,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ITR-Rubber-Tracks-scaled.jpg\",\"articleSection\":[\"Material rodante\",\"Revista\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/\",\"name\":\"Como medir e substituir as esteiras de borracha - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ITR-Rubber-Tracks-scaled.jpg\",\"datePublished\":\"2023-10-18T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:56:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ITR-Rubber-Tracks-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ITR-Rubber-Tracks-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/como-medir-e-substituir-as-esteiras-de-borracha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como medir e substituir as esteiras de borracha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como medir e substituir as esteiras de borracha - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/","og_locale":"pt_PT","og_type":"article","og_title":"Como medir e substituir as esteiras de borracha - ITR WORLD","og_description":"No setor das m\u00e1quinas de movimenta\u00e7\u00e3o de terras, as esteiras de borracha devem ser substitu\u00eddas quando est\u00e3o gastas ou danificadas, escolhendo as mais adequadas para cada tipo de m\u00e1quina e aplica\u00e7\u00e3o.","og_url":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2023-10-18T00:00:00+00:00","article_modified_time":"2026-09-01T09:56:36+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Rubber-Tracks-scaled.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assistenza@intersezione.com","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"Como medir e substituir as esteiras de borracha","datePublished":"2023-10-18T00:00:00+00:00","dateModified":"2026-09-01T09:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/"},"wordCount":1066,"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Rubber-Tracks-scaled.jpg","articleSection":["Material rodante","Revista"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/","url":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/","name":"Como medir e substituir as esteiras de borracha - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Rubber-Tracks-scaled.jpg","datePublished":"2023-10-18T00:00:00+00:00","dateModified":"2026-09-01T09:56:36+00:00","author":{"@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Rubber-Tracks-scaled.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Rubber-Tracks-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/pt-pt\/como-medir-e-substituir-as-esteiras-de-borracha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Como medir e substituir as esteiras de borracha"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/pt-pt\/#website","url":"https:\/\/itrworld.com\/pt-pt\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/itrworld.com\/pt-pt\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/pt-pt\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=9877"}],"version-history":[{"count":1,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9877\/revisions"}],"predecessor-version":[{"id":9881,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/posts\/9877\/revisions\/9881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media\/4965"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=9877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=9877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=9877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}