{"id":8753,"date":"2025-11-04T08:39:45","date_gmt":"2025-11-04T08:39:45","guid":{"rendered":"https:\/\/itrworld.com\/?page_id=8753"},"modified":"2026-06-29T17:03:47","modified_gmt":"2026-06-29T17:03:47","slug":"esteiras-e-sapatas-de-borracha","status":"publish","type":"page","link":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/","title":{"rendered":"Esteiras e sapatas de borracha"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#E5E5E5&#8243; bg_image=&#8221;1574&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;50&#8243; left_padding_desktop=&#8221;25px&#8221; top_padding_tablet=&#8221;50&#8243; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;50&#8243; left_padding_tablet=&#8221;4%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;4%&#8221; bottom_margin=&#8221;50&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#0A000000&#8243; color_overlay_2=&#8221;#000000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221; min_height_tablet=&#8221;600&#8243; min_height_phone=&#8221;600&#8243; min_height_desktop=&#8221;500&#8243; height_desktop=&#8221;500&#8243; height_tablet=&#8221;600&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_highlighted_text scribble_color=&#8221;#DC0813&#8243; style=&#8221;scribble&#8221; scribble_shape=&#8221;basic-underline&#8221; scribble_thickness=&#8221;regular&#8221; scribble_speed=&#8221;1.8s&#8221; scribble_easing=&#8221;ease_in_out&#8221; custom_font_size=&#8221;4vw&#8221; font_size_tablet=&#8221;7vw&#8221; font_line_height=&#8221;1.1em&#8221; text_direction=&#8221;default&#8221;]\n<h1><em>Esteiras e sapatas de borracha<\/em><\/h1>\n[\/nectar_highlighted_text][vc_custom_heading text=&#8221;Elevada ader\u00eancia, longa dura\u00e7\u00e3o&#8221; font_container=&#8221;tag:h1|font_size:32|text_align:left|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;300&#8243; custom_height_tablet=&#8221;0&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;content&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1782715511753{margin-bottom: 35px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h3>Constru\u00eddas para durar, concebidas para funcionar.<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1782715540287{padding-bottom: 50px !important;}&#8221; text_direction=&#8221;default&#8221;]As esteiras e sapatas de borracha ITR foram concebidas para satisfazer as necessidades das escavadeiras e das mini-p\u00e1s carregadeiras de rodas numa vasta gama de aplica\u00e7\u00f5es.<br \/>\nFabricadas com uma f\u00f3rmula especial que combina borracha natural e sint\u00e9tica, garantem uma durabilidade e um desempenho ideais em todas as condi\u00e7\u00f5es de trabalho. Solu\u00e7\u00f5es de concep\u00e7\u00e3o avan\u00e7adas e processos de fabrica\u00e7\u00e3o cuidadosos garantem uma excelente tra\u00e7\u00e3o, estabilidade e vibra\u00e7\u00e3o reduzida, melhorando a efici\u00eancia e o conforto do operador.<\/p>\n<p>A gama ITR inclui esteiras de borracha antivibra\u00e7\u00e3o especificamente concebidas para superf\u00edcies duras como asfalto, gravilha, concreto e pavimentos de pedra.<\/p>\n<p>As sapatas de borracha ITR est\u00e3o dispon\u00edveis nas vers\u00f5es bolton e clipon, bem como nas configura\u00e7\u00f5es standard e roadliner. Concebidas para m\u00e1xima adaptabilidade, integram-se facilmente na maioria dos ve\u00edculos com esteiras, oferecendo uma solu\u00e7\u00e3o confi\u00e1vel mesmo nos ambientes operacionais mais exigentes.<\/p>\n<p>Quer se trate de manuten\u00e7\u00e3o urbana de precis\u00e3o ou de trabalhos de escava\u00e7\u00e3o pesados, o compromisso da ITR com a qualidade faz toda a diferen\u00e7a.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;7138&#8243;][\/vc_column][\/vc_row][vc_section type=&#8221;full_width_background&#8221; flex_gap_desktop=&#8221;10px&#8221; text_color=&#8221;dark&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;50&#8243; top_margin=&#8221;50px&#8221; background_color=&#8221;#F5F5F7&#8243; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; content_layout=&#8221;flexbox&#8221; advanced_gradient_display_type=&#8221;linear&#8221; flex_layout_desktop=&#8221;column&#8221; flex_justify_content_desktop=&#8221;flex-start&#8221; flex_align_items_desktop=&#8221;flex-start&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;nowrap&#8221; flex_reverse_desktop=&#8221;false&#8221;][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;30px&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;25&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient=&#8221;linear-gradient(0deg, rgb(255,255,255) 16%, rgb(245,245,247) 71%)&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;5429&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Esteiras de borracha<\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient=&#8221;linear-gradient(0deg, rgb(255,255,255) 16%, rgb(245,245,247) 71%)&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;5648&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Solas em borracha e poliuretano<\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;10px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient=&#8221;linear-gradient(0deg, rgb(255,255,255) 16%, rgb(245,245,247) 71%)&#8221; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;advanced&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][image_with_animation image_url=&#8221;5645&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; margin_bottom=&#8221;0&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>Sapatas de borracha e poliuretano<\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#E5E5E5&#8243; bg_image=&#8221;1574&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;50&#8243; left_padding_desktop=&#8221;25px&#8221; top_padding_tablet=&#8221;50&#8243; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;50&#8243; left_padding_tablet=&#8221;4%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;4%&#8221; bottom_margin=&#8221;50&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#0A000000&#8243; color_overlay_2=&#8221;#000000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221; min_height_tablet=&#8221;600&#8243; min_height_phone=&#8221;600&#8243; min_height_desktop=&#8221;500&#8243; height_desktop=&#8221;500&#8243; height_tablet=&#8221;600&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8757,"parent":8670,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"page_category":[106],"page_tag":[],"class_list":["post-8753","page","type-page","status-publish","has-post-thumbnail","page_category-produtos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esteiras e sapatas de borracha - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esteiras e sapatas de borracha - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#E5E5E5&#8243; bg_image=&#8221;1574&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;50&#8243; left_padding_desktop=&#8221;25px&#8221; top_padding_tablet=&#8221;50&#8243; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;50&#8243; left_padding_tablet=&#8221;4%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;4%&#8221; bottom_margin=&#8221;50&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#0A000000&#8243; color_overlay_2=&#8221;#000000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221; min_height_tablet=&#8221;600&#8243; min_height_phone=&#8221;600&#8243; min_height_desktop=&#8221;500&#8243; height_desktop=&#8221;500&#8243; height_tablet=&#8221;600&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T17:03:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/cingoli-in-gomma-by-sigo-clean-dark.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1475\" \/>\n\t<meta property=\"og:image:height\" content=\"1056\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/\",\"name\":\"Esteiras e sapatas de borracha - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cingoli-in-gomma-by-sigo-clean-dark.jpg\",\"datePublished\":\"2025-11-04T08:39:45+00:00\",\"dateModified\":\"2026-06-29T17:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cingoli-in-gomma-by-sigo-clean-dark.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cingoli-in-gomma-by-sigo-clean-dark.jpg\",\"width\":1475,\"height\":1056,\"caption\":\"Rubber Tracks and Pads\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/produtos\\\/esteiras-e-sapatas-de-borracha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Esteiras e sapatas de borracha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esteiras e sapatas de borracha - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/","og_locale":"pt_PT","og_type":"article","og_title":"Esteiras e sapatas de borracha - ITR WORLD","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#E5E5E5&#8243; bg_image=&#8221;1574&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;50&#8243; left_padding_desktop=&#8221;25px&#8221; top_padding_tablet=&#8221;50&#8243; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;50&#8243; left_padding_tablet=&#8221;4%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;4%&#8221; bottom_margin=&#8221;50&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#0A000000&#8243; color_overlay_2=&#8221;#000000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221; min_height_tablet=&#8221;600&#8243; min_height_phone=&#8221;600&#8243; min_height_desktop=&#8221;500&#8243; height_desktop=&#8221;500&#8243; height_tablet=&#8221;600&#8243;][vc_column column_padding=&#8221;no-extra-padding&#8221;...","og_url":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_modified_time":"2026-06-29T17:03:47+00:00","og_image":[{"width":1475,"height":1056,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/cingoli-in-gomma-by-sigo-clean-dark.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/","url":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/","name":"Esteiras e sapatas de borracha - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/cingoli-in-gomma-by-sigo-clean-dark.jpg","datePublished":"2025-11-04T08:39:45+00:00","dateModified":"2026-06-29T17:03:47+00:00","breadcrumb":{"@id":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/cingoli-in-gomma-by-sigo-clean-dark.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/cingoli-in-gomma-by-sigo-clean-dark.jpg","width":1475,"height":1056,"caption":"Rubber Tracks and Pads"},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/pt-pt\/produtos\/esteiras-e-sapatas-de-borracha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/itrworld.com\/pt-pt\/products\/"},{"@type":"ListItem","position":3,"name":"Esteiras e sapatas de borracha"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/pt-pt\/#website","url":"https:\/\/itrworld.com\/pt-pt\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=8753"}],"version-history":[{"count":4,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8753\/revisions"}],"predecessor-version":[{"id":8879,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8753\/revisions\/8879"}],"up":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media\/8757"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8753"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/page_category?post=8753"},{"taxonomy":"page_tag","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/page_tag?post=8753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}