{"id":8668,"date":"2025-10-10T10:53:13","date_gmt":"2025-10-10T10:53:13","guid":{"rendered":"https:\/\/itrworld.com\/?page_id=8668"},"modified":"2026-06-28T13:52:52","modified_gmt":"2026-06-28T13:52:52","slug":"itr-global","status":"publish","type":"page","link":"https:\/\/itrworld.com\/pt-pt\/","title":{"rendered":"ITR Global"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0A0000&#8243; full_height=&#8221;yes&#8221; columns_placement=&#8221;bottom&#8221; video_bg=&#8221;use_video&#8221; video_webm=&#8221;https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/ITRWORLD-VIDEO-HOMEPAGE.webm&#8221; video_image=&#8221;163&#8243; background_video_loading=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;25px&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;force_gradient&#8221; enable_gradient=&#8221;true&#8221; color_overlay_2=&#8221;#0A0000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;50px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Os especialistas mundiais em movimenta\u00e7\u00e3o de terras.&#8221; font_container=&#8221;tag:h1|font_size:48px|text_align:left|color:%23FFFFFF|line_height:1.1&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_custom_heading text=&#8221;Garantimos a confiabilidade e a continuidade da atividade aos profissionais de todo o mundo.&#8221; font_container=&#8221;tag:p|font_size:28px|text_align:left|color:%23FFFFFF|line_height:1%2C5&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Descubra a gama&#8221; url=&#8221;https:\/\/itrworld.com\/pt-pt\/produtos\/&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;right&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;white&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Down2&#8243; icon_size=&#8221;48px&#8221; url=&#8221;#corporate&#8221; screen_reader_text=&#8221;Scorri in basso&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;corporate&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]<script async src=\"https:\/\/itrworld.com\/wp-content\/plugins\/usco-globe\/usco-globe.loader.js?v11\"><\/script>[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;&#8221; font_container=&#8221;tag:h2|font_size:28px|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]O Grupo ITR opera a n\u00edvel mundial no mercado de pe\u00e7as reposi\u00e7\u00e3o para m\u00e1quinas de constru\u00e7\u00e3o, desenvolvendo <strong>componentes e acess\u00f3rios<\/strong> para uma vasta gama de aplica\u00e7\u00f5es, <strong>desde m\u00e1quinas compactas a grandes equipamentos de minera\u00e7\u00e3o.<\/strong>[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; flex_sizing=&#8221;true&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_layout_tablet=&#8221;column&#8221; flex_gap_desktop=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;flexbox&#8221; flex_layout_desktop=&#8221;row&#8221; flex_justify_content_desktop=&#8221;space-between&#8221; flex_align_items_desktop=&#8221;center&#8221; flex_align_items_phone=&#8221;&#8221; flex_wrap_desktop=&#8221;wrap&#8221; flex_reverse_desktop=&#8221;false&#8221; gradient_type=&#8221;default&#8221; flex_layout_phone=&#8221;column&#8221;][nectar_btn size=&#8221;small&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#000000&#8243; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Saiba mais&#8221; url=&#8221;https:\/\/itrworld.com\/pt-pt\/o-grupo\/#about&#8221; margin_top=&#8221;25px&#8221;][nectar_btn size=&#8221;small&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#DC0813&#8243; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Contactar os nossos escrit\u00f3rios&#8221; url=&#8221;https:\/\/itrworld.com\/pt-pt\/contatos\/&#8221; margin_top=&#8221;25px&#8221; aria_label_text=&#8221;Contactar os nossos escrit\u00f3rios&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0A0000&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50px&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column top_padding_desktop=&#8221;15px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;15px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#E6E6E6&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-User&#8221; icon_size=&#8221;60px&#8221; class_name=&#8221;iconnumber&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;0&#8243; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;2527&#8243; subject=&#8221;PESSOAS&#8221; number_font_size=&#8221;62px&#8221;][\/vc_column][vc_column top_padding_desktop=&#8221;15px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;15px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#E6E6E6&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Gears-2&#8243; icon_size=&#8221;60px&#8221; class_name=&#8221;iconnumber&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;0&#8243; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;16&#8243; subject=&#8221;CENTROS DE PRODU\u00c7\u00c3O&#8221; number_font_size=&#8221;62px&#8221;][\/vc_column][vc_column top_padding_desktop=&#8221;15px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;15px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#E6E6E6&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Truck&#8221; icon_size=&#8221;60px&#8221; class_name=&#8221;iconnumber&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;0&#8243; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;93&#8243; subject=&#8221;CENTROS DE DISTRIBUI\u00c7\u00c3O&#8221; number_font_size=&#8221;62px&#8221;][\/vc_column][vc_column top_padding_desktop=&#8221;15px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;15px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#E6E6E6&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][nectar_icon icon_family=&#8221;iconsmind&#8221; icon_style=&#8221;default&#8221; icon_color_type=&#8221;color_scheme&#8221; icon_color=&#8221;Accent-Color&#8221; icon_padding=&#8221;20px&#8221; pointer_events=&#8221;all&#8221; icon_iconsmind=&#8221;iconsmind-Globe&#8221; icon_size=&#8221;60px&#8221; class_name=&#8221;iconnumber&#8221;][milestone heading_inherit=&#8221;default&#8221; subject_padding=&#8221;0&#8243; color=&#8221;Accent-Color&#8221; effect=&#8221;count&#8221; milestone_alignment=&#8221;default&#8221; number=&#8221;174&#8243; subject=&#8221;PA\u00cdSES ATENDIDOS&#8221; number_font_size=&#8221;62px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#FFFFFF&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100px&#8221; bottom_padding=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; id=&#8221;corporate&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;280&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Gli esperti mondiali nel movimento terra.&#8221; font_container=&#8221;tag:h2|font_size:28px|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Il Gruppo ITR \u00e8 leader nel mercato internazionale dei ricambi per macchine movimento terra, fornendo <b>componenti e attrezzature<\/b> progettati per un&#8217;ampia gamma di applicazioni, <b>dai mini escavatori alle grandi macchine da miniera<\/b>.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#000000&#8243; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/itrworld.com\/it\/il-gruppo\/#about&#8221; margin_top=&#8221;25px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#00000070&#8243; bg_image=&#8221;242&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50px&#8221; bottom_padding=&#8221;20px&#8221; left_padding_desktop=&#8221;25px&#8221; right_padding_desktop=&#8221;0&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#000000&#8243; overlay_strength=&#8221;0.95&#8243; gradient_direction=&#8221;left_b_to_right_t&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column right_padding_desktop=&#8221;50px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Uma gama completa para cada aplica\u00e7\u00e3o.&#8221; font_container=&#8221;tag:h2|font_size:28px|text_align:left|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Componentes e equipamentos concebidos para oferecer <strong>alto desempenho e longa dura\u00e7\u00e3o<\/strong>, gra\u00e7as ao controle direto da cadeia de abastecimento e ao investimento constante em <strong>pesquisa e qualidade<\/strong>.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#FFFFFF&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Saiba mais&#8221; url=&#8221;https:\/\/itrworld.com\/pt-pt\/produtos\/&#8221; margin_top=&#8221;25px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;prod-carousel&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][nectar_post_grid post_type=&#8221;custom&#8221; cpt_name=&#8221;page&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; flickity_controls=&#8221;next_prev_arrows_overlaid&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; desktop_small_cols_flickity=&#8221;default&#8221; tablet_cols_flickity=&#8221;default&#8221; phone_cols_flickity=&#8221;default&#8221; grid_item_spacing=&#8221;15px&#8221; grid_item_height=&#8221;30vh&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;full&#8221; aspect_ratio_image_size=&#8221;yes&#8221; custom_image_aspect_ratio=&#8221;4-3&#8243; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;default&#8221; heading_tag_render=&#8221;default&#8221; category_position=&#8221;default&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#FFFFFF&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;15px&#8221; shadow_on_hover=&#8221;yes&#8221; read_more_button=&#8221;yes&#8221; custom_query_tax=&#8221;77&#8243; display_type=&#8221;carousel&#8221; custom_font_size=&#8221;28px&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#FFFFFF&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100px&#8221; bottom_padding=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;Ovunque operiate, noi vi aiutiamo ad andare avanti.&#8221; font_container=&#8221;tag:h2|font_size:28px|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]La nostra capillare rete globale ci consente di rifornire rapidamente le scorte e di rispondere pi\u00f9 velocemente alle esigenze dei clienti.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#000000&#8243; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Scopri di pi\u00f9&#8221; url=&#8221;https:\/\/itrworld.com\/it\/contatti\/&#8221; margin_top=&#8221;25px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F5F5F7&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;75&#8243; bottom_padding=&#8221;75&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;section-brands section-brands-black&#8221; id=&#8221;brands&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#E0DFDF&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;100px&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;speech&#8221;][vc_column top_padding_desktop=&#8221;15px&#8221; constrain_group_100=&#8221;yes&#8221; bottom_padding_desktop=&#8221;15px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#000000&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;15px&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_color=&#8221;#E6E6E6&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][vc_custom_heading text=&#8221;A for\u00e7a do Grupo&#8221; font_container=&#8221;tag:h2|font_size:36px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;50&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;5417&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;322&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;400px&#8221; bottom_padding=&#8221;50px&#8221; top_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient=&#8221;linear-gradient(180deg, rgba(15,18,7,0) 10%, rgba(15, 18, 7, 0.5) 55%, rgba(15, 18, 7, 255) 83%)&#8221; advanced_gradient_angle=&#8221;180&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;advanced&#8221; shape_type=&#8221;&#8221; advanced_gradient_display_type=&#8221;linear&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; font_color=&#8221;#FFFFFF&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Sustentabilidade&#8221; font_container=&#8221;tag:h2|font_size:36px|text_align:center|color:%23FFFFFF&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]Um compromisso concreto de crescimento respons\u00e1vel: a preocupa\u00e7\u00e3o com as <strong>pessoas<\/strong>, a redu\u00e7\u00e3o do <strong>impacto ambiental<\/strong> e a <strong>governan\u00e7a transparente<\/strong> orientam todas as atividades do Grupo ITR.[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#FFFFFF&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;default_arrow&#8221; text=&#8221;Saiba mais&#8221; url=&#8221;https:\/\/itrworld.com\/pt-pt\/sustentabilidade\/&#8221; margin_top=&#8221;25px&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F5F5F7&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;50px&#8221; bottom_padding=&#8221;50px&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;15px&#8221; row_border_radius_applies=&#8221;inner&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;magazineloop&#8221; id=&#8221;articles-loop&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column bottom_padding_desktop=&#8221;25&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;articles-loop&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][tabbed_section style=&#8221;minimal&#8221; tab_change_animation=&#8221;fade&#8221; alignment=&#8221;left&#8221; spacing=&#8221;default&#8221; tab_color=&#8221;Accent-Color&#8221; vs_content_animation=&#8221;fade&#8221; vs_link_animation=&#8221;opacity&#8221; vs_navigation_alignment=&#8221;left&#8221; vs_navigation_width_2=&#8221;25%&#8221; vs_navigation_func=&#8221;default&#8221; vs_navigation_width=&#8221;regular&#8221; vs_navigation_spacing=&#8221;15px&#8221; vs_navigation_mobile_display=&#8221;visible&#8221; vs_tab_spacing=&#8221;5%&#8221; cta_button_style=&#8221;accent-color&#8221; icon_size=&#8221;24&#8243;][tab icon_family=&#8221;none&#8221; title=&#8221;Revista&#8221; id=&#8221;1782654336050-4&#8243; tab_id=&#8221;1782654336051-6&#8243;][nectar_post_grid post_type=&#8221;post&#8221; blog_category=&#8221;magazine&#8221; blog_starting_category=&#8221;all&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; flickity_controls=&#8221;none&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; desktop_small_cols_flickity=&#8221;2&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; grid_item_spacing=&#8221;15px&#8221; grid_item_height=&#8221;30vh&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;large&#8221; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h3&#8243; heading_tag_render=&#8221;h3&#8243; category_position=&#8221;default&#8221; display_excerpt=&#8221;yes&#8221; excerpt_display=&#8221;desktop_only&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#FFFFFF&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;15px&#8221; shadow_on_hover=&#8221;yes&#8221; read_more_button=&#8221;yes&#8221; posts_per_page=&#8221;9&#8243; display_type=&#8221;carousel&#8221; css_class_name=&#8221;gridmagazine&#8221; excerpt_length=&#8221;10&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;accent-color&#8221; text_color=&#8221;#FFFFFF&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; icon_alignment=&#8221;left&#8221; position_desktop=&#8221;relative&#8221; bottom_position_tablet=&#8221;0&#8243; link_text=&#8221;Descubra&#8221; padding_top=&#8221;10&#8243; padding_bottom=&#8221;10&#8243; padding_left=&#8221;20&#8243; padding_right=&#8221;20&#8243; url=&#8221;https:\/\/itrworld.com\/it\/newsroom\/#magazine&#8221; aria_label_text=&#8221;Discover more&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Eventos&#8221; id=&#8221;1782654336108-7&#8243; tab_id=&#8221;1782654336109-7&#8243;][nectar_post_grid post_type=&#8221;custom&#8221; cpt_name=&#8221;post&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; flickity_controls=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; desktop_small_cols_flickity=&#8221;2&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; grid_item_spacing=&#8221;15px&#8221; grid_item_height=&#8221;30vh&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;large&#8221; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h3&#8243; heading_tag_render=&#8221;h3&#8243; category_position=&#8221;default&#8221; display_excerpt=&#8221;yes&#8221; excerpt_display=&#8221;desktop_only&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#FFFFFF&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;15px&#8221; shadow_on_hover=&#8221;yes&#8221; posts_per_page=&#8221;6&#8243; display_type=&#8221;carousel&#8221; css_class_name=&#8221;gridmagazine noclick&#8221; custom_query_tax=&#8221;26&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;accent-color&#8221; text_color=&#8221;#FFFFFF&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; icon_alignment=&#8221;left&#8221; position_desktop=&#8221;relative&#8221; bottom_position_desktop=&#8221;25&#8243; bottom_position_tablet=&#8221;0&#8243; link_text=&#8221;Descubra&#8221; padding_top=&#8221;10&#8243; padding_bottom=&#8221;10&#8243; padding_left=&#8221;20&#8243; padding_right=&#8221;20&#8243; url=&#8221;https:\/\/itrworld.com\/it\/newsroom\/#events&#8221; aria_label_text=&#8221;Discover more&#8221;][\/tab][tab icon_family=&#8221;none&#8221; title=&#8221;Not\u00edcias&#8221; id=&#8221;1782654336144-7&#8243; tab_id=&#8221;1782654336144-3&#8243;][nectar_post_grid post_type=&#8221;custom&#8221; cpt_name=&#8221;post&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; flickity_controls=&#8221;default&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; columns=&#8221;3&#8243; columns_tablet=&#8221;default&#8221; columns_phone=&#8221;default&#8221; desktop_small_cols_flickity=&#8221;2&#8243; tablet_cols_flickity=&#8221;2&#8243; phone_cols_flickity=&#8221;1&#8243; grid_item_spacing=&#8221;15px&#8221; grid_item_height=&#8221;30vh&#8221; 3_col_masonry_layout=&#8221;default&#8221; image_size=&#8221;large&#8221; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_stagger=&#8221;90&#8243; animation_easing=&#8221;default&#8221; heading_tag=&#8221;h3&#8243; heading_tag_render=&#8221;h3&#8243; category_position=&#8221;default&#8221; display_excerpt=&#8221;yes&#8221; excerpt_display=&#8221;desktop_only&#8221; additional_meta_size=&#8221;default&#8221; custom_fields_location=&#8221;before_post_meta&#8221; grid_style=&#8221;content_under_image&#8221; card_design=&#8221;yes&#8221; card_bg_color=&#8221;#FFFFFF&#8221; content_under_image_text_align=&#8221;left&#8221; text_color=&#8221;dark&#8221; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;15px&#8221; shadow_on_hover=&#8221;yes&#8221; read_more_button=&#8221;yes&#8221; posts_per_page=&#8221;3&#8243; display_type=&#8221;carousel&#8221; css_class_name=&#8221;gridmagazine&#8221; custom_query_tax=&#8221;2&#8243; excerpt_length=&#8221;20&#8243;][nectar_cta btn_style=&#8221;basic&#8221; heading_tag=&#8221;span&#8221; link_type=&#8221;regular&#8221; button_color=&#8221;accent-color&#8221; text_color=&#8221;#FFFFFF&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; icon_family=&#8221;none&#8221; icon_alignment=&#8221;left&#8221; position_desktop=&#8221;relative&#8221; bottom_position_desktop=&#8221;25&#8243; bottom_position_tablet=&#8221;0&#8243; link_text=&#8221;Descubra&#8221; padding_top=&#8221;10&#8243; padding_bottom=&#8221;10&#8243; padding_left=&#8221;20&#8243; padding_right=&#8221;20&#8243; url=&#8221;https:\/\/itrworld.com\/it\/newsroom\/#news&#8221; aria_label_text=&#8221;Discover more&#8221;][\/tab][\/tabbed_section][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0A0000&#8243; full_height=&#8221;yes&#8221; columns_placement=&#8221;bottom&#8221; video_bg=&#8221;use_video&#8221; video_webm=&#8221;https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/ITRWORLD-VIDEO-HOMEPAGE.webm&#8221; video_image=&#8221;163&#8243; background_video_loading=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;25px&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;force_gradient&#8221; enable_gradient=&#8221;true&#8221; color_overlay_2=&#8221;#0A0000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"page_category":[],"page_tag":[],"class_list":["post-8668","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITR Global - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/pt-pt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITR Global - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0A0000&#8243; full_height=&#8221;yes&#8221; columns_placement=&#8221;bottom&#8221; video_bg=&#8221;use_video&#8221; video_webm=&#8221;https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/ITRWORLD-VIDEO-HOMEPAGE.webm&#8221; video_image=&#8221;163&#8243; background_video_loading=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;25px&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;force_gradient&#8221; enable_gradient=&#8221;true&#8221; color_overlay_2=&#8221;#0A0000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/pt-pt\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-28T13:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"name\":\"ITR Global - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2025-10-10T10:53:13+00:00\",\"dateModified\":\"2026-06-28T13:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITR Global\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITR Global - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/pt-pt\/","og_locale":"pt_PT","og_type":"article","og_title":"ITR Global - ITR WORLD","og_description":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#0A0000&#8243; full_height=&#8221;yes&#8221; columns_placement=&#8221;bottom&#8221; video_bg=&#8221;use_video&#8221; video_webm=&#8221;https:\/\/itrworld.com\/wp-content\/uploads\/2025\/12\/ITRWORLD-VIDEO-HOMEPAGE.webm&#8221; video_image=&#8221;163&#8243; background_video_loading=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;25px&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;force_gradient&#8221; enable_gradient=&#8221;true&#8221; color_overlay_2=&#8221;#0A0000&#8243; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;top_to_bottom&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221;...","og_url":"https:\/\/itrworld.com\/pt-pt\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_modified_time":"2026-06-28T13:52:52+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itrworld.com\/pt-pt\/","url":"https:\/\/itrworld.com\/pt-pt\/","name":"ITR Global - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/pt-pt\/#website"},"datePublished":"2025-10-10T10:53:13+00:00","dateModified":"2026-06-28T13:52:52+00:00","breadcrumb":{"@id":"https:\/\/itrworld.com\/pt-pt\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/pt-pt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/pt-pt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"ITR Global"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/pt-pt\/#website","url":"https:\/\/itrworld.com\/pt-pt\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=8668"}],"version-history":[{"count":4,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8668\/revisions"}],"predecessor-version":[{"id":8688,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/pages\/8668\/revisions\/8688"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=8668"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/page_category?post=8668"},{"taxonomy":"page_tag","embeddable":true,"href":"https:\/\/itrworld.com\/pt-pt\/wp-json\/wp\/v2\/page_tag?post=8668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}