{"id":9481,"date":"2021-03-02T00:00:00","date_gmt":"2021-03-02T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/"},"modified":"2026-09-01T09:49:09","modified_gmt":"2026-09-01T09:49:09","slug":"chemises-pour-moteurs-diesels-avantages-et-utilisation","status":"publish","type":"post","link":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/","title":{"rendered":"Chemises pour moteurs diesels: avantages et utilisation"},"content":{"rendered":"<h2>Comment pr\u00e9server le moteur: importance<br \/>\ndes chemises dans le syst\u00e8me de propulsion.<\/h2>\n<h4>Le fonctionnement correct du moteur est l&rsquo;un des \u00e9l\u00e9ments essentiels pour assurer les performances des engins de chantier tels que les excavateurs, les mini-excavateurs, les bulldozers, les pelles sur pneus et les bennes qui, de par leurs applications, doivent r\u00e9pondre \u00e0 des rythmes de sollicitation \u00e9lev\u00e9s.<\/h4>\n<p><span>Le choix pond\u00e9r\u00e9 et la maintenance pr\u00e9cise des composants du moteur peuvent prolonger la dur\u00e9e de vie de l&rsquo;engin, diminuer les co\u00fbts de maintenance et, en r\u00e9duisant les arr\u00eats pour panne, augmenter la productivit\u00e9.&nbsp;Dans cet article, nous illustrons le comment du pourquoi&nbsp;les <\/span><span>chemises ou liners<\/span><span>jouent un r\u00f4le essentiel<\/span><span>.<\/span><\/p>\n<h3 align=\"left\">Types de chemises pour cylindres et avantages de leur utilisation<\/h3>\n<p>&nbsp;<\/p>\n<table style=\"float: left;\" align=\"center\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Komatsu-6240-21-2220.jpg\" alt=\"Cylinder liner ITR Komatsu 6240 21 2220\" width=\"152\" height=\"228\"><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Caterpillar-1979322.jpg\" alt=\"Cylinder liner ITR Caterpillar 1979322\" width=\"149\" height=\"223\"><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Caterpillar-1105800.jpg\" alt=\"Cylinder liner ITR Caterpillar 1105800\" width=\"149\" height=\"222\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">&nbsp;<\/p>\n<p align=\"left\">Les chemises sont des rev\u00eatements cylindriques en mesure de maintenir une fine couche d&rsquo;huile sur la surface de sa paroi interne qui, ins\u00e9r\u00e9es \u00e0 l&rsquo;int\u00e9rieur des cylindres du bloc-cylindres, le prot\u00e8gent contre l&rsquo;usure caus\u00e9e par le glissement des pistons. Dans les blocs-cylindres des engins industriels, diff\u00e9remment des autres applications moins contraignantes, dans la plupart des cas, les constructeurs ont tendance \u00e0 utiliser des cylindres chemis\u00e9s plut\u00f4t que de faire travailler le piston directement sur les parois du bloc moteur.<\/p>\n<p align=\"left\">Il existe <strong>2 types principaux de chemises<\/strong>: le <strong>premier type<\/strong> ne pr\u00e9voit aucun contact direct avec la paroi du cylindre du bloc. <strong>Dans ce cas, la chemise est baign\u00e9e par le flux du liquide de refroidissement<\/strong> et pour cette raison, ce type est appel\u00e9 \u00ab&nbsp;<em><strong>chemise humide<\/strong><\/em>&nbsp;\u00bb. Le <strong>deuxi\u00e8me type<\/strong> correspond par contre \u00e0 la \u00ab&nbsp;<em><strong>chemise s\u00e8che<\/strong><\/em>&nbsp;\u00bb, \u00e9galement appel\u00e9e \u00ab&nbsp;<em><strong>manchon<\/strong><\/em>&nbsp;\u00bb qui en fait est constitu\u00e9e d&rsquo;un cylindre de faible \u00e9paisseur qui est int\u00e9gr\u00e9 \u00e0 l&rsquo;int\u00e9rieur du bloc-cylindres et dont <strong>les parois touchent directement le cylindre<\/strong>.<\/p>\n<p>L&rsquo;adoption de cylindres chemis\u00e9s de la part des fabricants est li\u00e9e aux <strong>avantages<\/strong> associ\u00e9s \u00e0 ce syst\u00e8me, \u00e0 savoir:<\/p>\n<ul>\n<li><strong>R\u00e9sistance plus \u00e9lev\u00e9e<\/strong>. L&#8217;emploi de chemises s\u00e9par\u00e9es du bloc-cylindres, permet d&rsquo;utiliser des mat\u00e9riaux sp\u00e9cifiques et plus performants par rapport \u00e0 ceux utilis\u00e9s dans la fabrication du bloc m\u00eame. Les chemises sont en effet normalement fabriqu\u00e9es en alliages de fonte qui int\u00e8grent des \u00e9l\u00e9ments ayant des propri\u00e9t\u00e9s de lubrification naturelle, comme le graphite. D&rsquo;autres \u00e9l\u00e9ments comme le chrome, le vanadium et le molybd\u00e8ne, contribuent \u00e0 garantir une meilleure r\u00e9sistance contre la corrosion et l&rsquo;usure due aux temp\u00e9ratures \u00e9lev\u00e9es.\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Maintenance plus facile.<\/strong> Lorsque les chemises sont d\u00e9t\u00e9rior\u00e9es, vous pouvez les remplacer plus facilement au lieu de remplacer l&rsquo;ensemble du bloc-cylindres.\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Meilleure conductivit\u00e9 thermique<\/strong>. \u00c0 la temp\u00e9rature de fonctionnement, les chemises chauffent plus que les cylindres et doivent pouvoir se dilater \u00e0 la fois diam\u00e9tralement et longitudinalement. Si les chemises sont coul\u00e9es avec les cylindres, cela entra\u00eenerait des contraintes thermiques qui provoqueraient la rupture des mat\u00e9riaux.\n<\/li>\n<li><strong>Faible probabilit\u00e9 de d\u00e9fauts<\/strong>. Plus le coulage est complexe, plus il est difficile de produire des surfaces homog\u00e8nes avec de faibles contraintes r\u00e9siduelles.<\/li>\n<\/ul>\n<h3>Quelles caract\u00e9ristiques doivent poss\u00e9der les chemises moteur pour \u00eatre performantes?<\/h3>\n<p>Les chemises sont soumises \u00e0 plusieurs contraintes:<\/p>\n<ul>\n<li>m\u00e9caniques, en raison de la pression de combustion;<\/li>\n<li>thermiques, en raison de la temp\u00e9rature \u00e9lev\u00e9e produite par le processus de combustion;<\/li>\n<li>d&rsquo;usure, celle-ci li\u00e9e surtout \u00e0 3&nbsp;facteurs:\n<ul>\n<li>abrasion, qui varie en fonction de l&rsquo;efficacit\u00e9 des filtres de l&rsquo;air et de l&rsquo;huile,<\/li>\n<li>corrosion, due aux composants produits par la combustion,<\/li>\n<li>frottement ou friction, suite \u00e0 une lubrification insuffisante.\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Pour toutes ces raisons, le processus de production de ces composants est essentiel et leur conception doit r\u00e9pondre \u00e0 des caract\u00e9ristiques sp\u00e9cifiques pour pr\u00e9server le moteur et prolonger sa dur\u00e9e de vie, \u00e0 savoir:<\/p>\n<ul>\n<li><strong>propri\u00e9t\u00e9s anticorrosion et de r\u00e9sistance \u00e9lev\u00e9es,<\/strong><\/li>\n<li><strong>faible friction,<\/strong><\/li>\n<li><strong>haute pr\u00e9cision.\n<p><\/strong><\/li>\n<\/ul>\n<p>Pour r\u00e9duire la friction et prolonger la vie du moteur, une caract\u00e9ristique essentielle de la chemise est celle du trait crois\u00e9 pr\u00e9sent sur la paroi. La rayure de la surface a la fonction de maintenir une quantit\u00e9 d&rsquo;huile suffisante sur les parois internes de la chemise, tout en assurant une <strong>lubrification ad\u00e9quate dans les points de contact des segments avec la chemise <\/strong>m\u00eame. En g\u00e9n\u00e9ral, on estime que l<strong>&lsquo;angle d&rsquo;intersection correct pour la rayure des parois<\/strong> est de <strong>45\u00b0<\/strong> environ, car ceci favorise une <strong>lubrification homog\u00e8ne<\/strong> et donc une <strong>dur\u00e9e sup\u00e9rieure des surfaces<\/strong>; toutefois, les solutions incluent \u00e9galement des angles diff\u00e9rents selon le mat\u00e9riau et l&rsquo;utilisation.&nbsp;Enfin, les \u00e9l\u00e9ments qui contribuent \u00e0 augmenter la r\u00e9sistance et \u00e0 diminuer l&rsquo;usure des surfaces des chemises comprennent le cintrage des brides et le rev\u00eatement anticorrosion de la paroi ext\u00e9rieure.<\/p>\n<h3>Comment installer correctement les chemises \u00e0 l&rsquo;int\u00e9rieur des cylindres?<\/h3>\n<p>Vous trouverez ci-dessous les \u00e9tapes principales et les consignes pour installer correctement les chemises \u00e0 l&rsquo;int\u00e9rieur des cylindres afin d&rsquo;\u00e9viter les pannes et l&rsquo;usure pr\u00e9coce.<\/p>\n<ol>\n<li>Nettoyer soigneusement le bloc-cylindres: les salet\u00e9s coinc\u00e9es peuvent entra\u00eener la rupture de la bride.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-1.jpg\" alt=\"Cylinder liner ITR Usco 1\" width=\"527\" height=\"351\"><\/p>\n<\/li>\n<li>V\u00e9rifier l&rsquo;absence de bavures ou de mat\u00e9riaux saillants; le cas \u00e9ch\u00e9ant, les \u00e9liminer pour \u00e9viter les probl\u00e8mes au niveau des joints.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-3.jpg\" alt=\"Cylinder liner ITR Usco 3\" width=\"529\" height=\"297\"><\/p>\n<\/li>\n<li>Ins\u00e9rer les chemises dans le bloc-cylindres sans joints ni autres mastics et v\u00e9rifier la protrusion correcte de la bride; si n\u00e9cessaire, faites-la pivoter pour trouver la configuration correcte.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-4.jpg\" alt=\"Cylinder liner ITR Usco 4\" width=\"530\" height=\"353\"><\/p>\n<\/li>\n<li>Lorsque la position de la chemise est correcte, retirez-la apr\u00e8s application d&rsquo;un rep\u00e8re d&rsquo;alignement sur la chemise et sur le bloc-cylindres pour pouvoir la r\u00e9ins\u00e9rer dans la m\u00eame position.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-5.jpg\" alt=\"Cylinder liner ITR Usco 5\" width=\"531\" height=\"354\"><\/p>\n<\/li>\n<li>Ins\u00e9rer les joints tout en \u00e9vitant les torsions car elles peuvent d\u00e9former la chemise, g\u00e9n\u00e9rer une friction sur celle-ci ou r\u00e9duire le jeu entre piston et chemise.<br \/> Plusieurs installateurs consid\u00e8rent que pour faciliter l&rsquo;op\u00e9ration, les joints doivent \u00eatre lubrifi\u00e9s ou recouverts d&rsquo;une solution savonneuse avant de les installer. La m\u00e9thode correcte consiste par contre \u00e0 installer le joint \u00ab&nbsp;\u00e0 sec&nbsp;\u00bb en ins\u00e9rant une tige cylindrique (par ex. un tournevis) et en la d\u00e9pla\u00e7ant tout le long de la circonf\u00e9rence du joint pour le faire adh\u00e9rer de mani\u00e8re uniforme. Seulement lorsque cette \u00e9tape est compl\u00e9t\u00e9e, vous pouvez lubrifier les diff\u00e9rents composants.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-6.jpg\" alt=\"Cylinder liner ITR Usco 6\" width=\"534\" height=\"356\"><\/p>\n<\/li>\n<li>Immerger le joint d&rsquo;\u00e9tanch\u00e9it\u00e9 dans de l&rsquo;huile SAE 30 propre. Installez-le sur la chemise qui devra \u00eatre ins\u00e9r\u00e9e dans le bloc-cylindres imm\u00e9diatement, avant que le joint d&rsquo;\u00e9tanch\u00e9it\u00e9 ne se dilate.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-7.jpg\" alt=\"Cylinder liner ITR Usco 7\" width=\"533\" height=\"561\"><\/p>\n<\/li>\n<li>V\u00e9rifier que le rep\u00e8re sur la chemise fait auparavant soit align\u00e9 avec le rep\u00e8re sur le bloc. Utilisez l&rsquo;outil sp\u00e9cial pour pousser la chemise dans sa position.\n<p><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Cylinder-liner-ITR-Usco-8.jpg\" alt=\"Cylinder liner ITR Usco 8\" width=\"535\" height=\"356\"><\/p>\n<\/li>\n<li>R\u00e9p\u00e9ter les \u00e9tapes pour toutes les chemises disponibles.<\/li>\n<\/ol>\n<h3 align=\"left\">Chemises pour cylindres ITR<\/h3>\n<p align=\"left\">Le choix et l&rsquo;utilisation correcte d&rsquo;un seul petit composant peuvent impacter les performances et le cycle de vie des engins de chantier. Pour cette m\u00eame raison, il est important de pouvoir compter sur un partenaire expert.<br \/><strong>ITR Usco propose une vaste gamme de chemises<\/strong>, avec al\u00e9sages compris entre 94&nbsp;mm et 170&nbsp;mm, pour <strong>Caterpillar<strong>\u00ae<\/strong>, Komatsu<strong>\u00ae<\/strong>, Volvo<strong>\u00ae<\/strong>, Hitachi<strong>\u00ae<\/strong> et JCB<strong>\u00ae<\/strong><\/strong>. <a href=\"https:\/\/itrworld.com\/fr\/contacts\/\" target=\"_blank\"><strong>Contactez notre personnel<\/strong><\/a> pour plus d&rsquo;informations sur les types et les mat\u00e9riaux plus appropri\u00e9s \u00e0 vos applications.<\/p>\n<p align=\"left\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment pr\u00e9server le moteur: importance<br \/>\ndes chemises dans le syst\u00e8me de propulsion.<\/p>\n","protected":false},"author":1,"featured_media":5104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[97,213],"tags":[],"class_list":["post-9481","post","type-post","status-publish","format-standard","has-post-thumbnail","category-magazine","category-pieces-mecaniques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chemises pour moteurs diesels: avantages et utilisation - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chemises pour moteurs diesels: avantages et utilisation - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"Comment pr\u00e9server le moteur: importance des chemises dans le syst\u00e8me de propulsion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-02T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:49:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"Chemises pour moteurs diesels: avantages et utilisation\",\"datePublished\":\"2021-03-02T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:49:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/\"},\"wordCount\":1282,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"articleSection\":[\"Magazine\",\"Pi\u00e8ces m\u00e9caniques\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/\",\"name\":\"Chemises pour moteurs diesels: avantages et utilisation - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"datePublished\":\"2021-03-02T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:49:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Modello-distributivo-ITR-Usco.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/chemises-pour-moteurs-diesels-avantages-et-utilisation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chemises pour moteurs diesels: avantages et utilisation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/fr\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chemises pour moteurs diesels: avantages et utilisation - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/","og_locale":"fr_FR","og_type":"article","og_title":"Chemises pour moteurs diesels: avantages et utilisation - ITR WORLD","og_description":"Comment pr\u00e9server le moteur: importance des chemises dans le syst\u00e8me de propulsion.","og_url":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2021-03-02T00:00:00+00:00","article_modified_time":"2026-09-01T09:49:09+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"assistenza@intersezione.com","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/fr\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"Chemises pour moteurs diesels: avantages et utilisation","datePublished":"2021-03-02T00:00:00+00:00","dateModified":"2026-09-01T09:49:09+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/"},"wordCount":1282,"image":{"@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","articleSection":["Magazine","Pi\u00e8ces m\u00e9caniques"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/","url":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/","name":"Chemises pour moteurs diesels: avantages et utilisation - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","datePublished":"2021-03-02T00:00:00+00:00","dateModified":"2026-09-01T09:49:09+00:00","author":{"@id":"https:\/\/itrworld.com\/fr\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Modello-distributivo-ITR-Usco.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/fr\/chemises-pour-moteurs-diesels-avantages-et-utilisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Chemises pour moteurs diesels: avantages et utilisation"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/fr\/#website","url":"https:\/\/itrworld.com\/fr\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/itrworld.com\/fr\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/fr\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/posts\/9481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/comments?post=9481"}],"version-history":[{"count":1,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/posts\/9481\/revisions"}],"predecessor-version":[{"id":9483,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/posts\/9481\/revisions\/9483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/media\/5104"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/media?parent=9481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/categories?post=9481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/fr\/wp-json\/wp\/v2\/tags?post=9481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}