{"id":9681,"date":"2021-10-14T00:00:00","date_gmt":"2021-10-14T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/"},"modified":"2026-09-01T09:52:42","modified_gmt":"2026-09-01T09:52:42","slug":"itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr","status":"publish","type":"post","link":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/","title":{"rendered":"ITR Industries: centro productivo por excelencia del Grupo USCO ITR"},"content":{"rendered":"<h2>ITR Industries satisface completamente la demanda del Grupo USCO ITR para la producci\u00f3n de componentes para el tren de rodaje destinados al sector de la posventa y como piezas originales para los m\u00e1s importantes fabricantes de maquinaria de movimiento de tierras.<\/h2>\n<h4>En el centro de la cadena de suministro de ITR (junto con ITR Meccanica, el polo de producci\u00f3n de piezas de recambio) se encuentra ITR Industries. Tiene plantas en Corea del Sur que producen cadenas, zapatas, segmentos y rodillos. Tambi\u00e9n tienen establecimientos en China dedicados a la producci\u00f3n de rodillos, ruedas tensoras de orugas y ruedas motrices. En este art\u00edculo hablaremos precisamente de la empresa china.\u00a0<\/h4>\n<p dir=\"ltr\"><span>Con su <\/span><strong>establecimiento de 54 000 <strong>m<sup>2<\/sup><\/strong><\/strong><span><strong>, 29 000 de ellos cubiertos<\/strong>, <\/span><span>la empresa se beneficia de una <\/span><span><strong>posici\u00f3n estrat\u00e9gica que le permite reabastecer f\u00e1cilmente a M\u00f3dena y a las otras filiales ITR en el mundo<\/strong>.<\/span><span> Est\u00e1 situada en la regi\u00f3n china reconocida por su excelencia en el sector del autom\u00f3vil y la electr\u00f3nica de precisi\u00f3n: General Motors\u00ae, Hyundai\u00ae, Apple\u00ae y LG\u00ae son algunas de las marcas que poseen all\u00ed importantes centros de producci\u00f3n.&nbsp;<\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p dir=\"ltr\"><span>Se trata de un entorno de fabricaci\u00f3n bien consolidado y en constante <\/span><strong>expansi\u00f3n<\/strong><span>. Recientemente se han realizado numerosas inversiones para el <\/span><span><strong>cumplimiento de la normativa<\/strong> <strong>medioambienta<\/strong>l<\/span><span>, convirti\u00e9ndola en un centro de vanguardia en consonancia con las normativas m\u00e1s recientes y restrictivas en este \u00e1mbito. Esto ha supuesto una oportunidad para <\/span><strong>redise\u00f1ar diversas \u00e1reas<\/strong><span>, aplicando en gran medida los llamados enfoques \u00ablean\u00bb para mejorar la gesti\u00f3n de los procesos de la empresa y reducir los residuos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span id=\"docs-internal-guid-6c116f28-7fff-220b-d283-58769466f084\"><span>La fundici\u00f3n, por ejemplo, ha sido redise\u00f1ada conforme a una <\/span><strong>\u00f3ptica de flujo <\/strong><span>que automatiza el proceso de manipulaci\u00f3n de moldes. Adem\u00e1s, los equipos resultantes tienen capacidad para <\/span><strong>reducir las emisiones<\/strong><span>, lo que confiere a ITR Industries China una ventaja competitiva frente a los retos de las pr\u00f3ximas d\u00e9cadas.<\/span><\/span><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/wvs-hFooXOQ?si=bLEqJUGA9c426-Ir\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<h3 dir=\"ltr\"><span>Control completo de la producci\u00f3n de rodillos, ruedas motrices y ruedas tensoras de las orugas.<\/span><\/h3>\n<p dir=\"ltr\"><span>La empresa china produce principalmente <\/span><strong>rodillos,&nbsp;ruedas motrices y ruedas tensoras de oruga<\/strong><span><strong> para tren de rodaje<\/strong>.&nbsp;<\/span>Los componentes que se fabrican aqu\u00ed satisfacen plenamente las necesidades del Grupo USCO ITR, lo que convierte a ITR Industries en una pieza clave en la cadena de suministro de rodaje ITR.&nbsp;<\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p dir=\"ltr\"><span>El proceso de producci\u00f3n de ruedas motrices y ruedas tensoras comienza con la elaboraci\u00f3n de las materias primas. Los hornos de fundici\u00f3n in situ proporcionan a la empresa una considerable autonom\u00eda, adem\u00e1s de garantizar un procesamiento de alta calidad. La producci\u00f3n pasa por una secuencia de procesos mec\u00e1nicos CNC y tratamientos t\u00e9rmicos a medida que los componentes avanzan hacia las estaciones de montaje y revestimiento. Estas operaciones tambi\u00e9n se han <\/span><strong>reordenado<\/strong><span> recientemente en el marco de la pol\u00edtica de mejora continua aplicada por equipos dedicados a la <\/span><strong>reducci\u00f3n de residuos<\/strong><span>. El nuevo enfoque tiene como objetivo espec\u00edfico limitar los llamados siete \u00abMuda\u00bb: El t\u00e9rmino MUDA designa al desperdicio en t\u00e9rminos de esperas, transportes, sobreproducci\u00f3n, reservas excesivas, manipulaci\u00f3n, defectos y operaciones \u201cin\u00fatiles\u201d en el proceso.<\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p><span id=\"docs-internal-guid-7c63de34-7fff-e7b3-f7d9-ab79625a1552\"><span>Los <\/span><strong>rodillos<\/strong><span> se fabrican directamente de aleaciones de acero forjado. Despu\u00e9s son sometidos a producci\u00f3n mec\u00e1nica y a tratamiento t\u00e9rmico para proporcionarles las <\/span><strong>caracter\u00edsticas <\/strong><span>adecuadas de resistencia al desgaste y tenacidad.&nbsp; En particular, algunas de las inversiones m\u00e1s recientes se han destinado a mejorar precisamente las prestaciones del <\/span><strong>tratamiento t\u00e9rmico<\/strong><span>, centro del bagaje t\u00e9cnico de ITR, para garantizar los est\u00e1ndares cada vez m\u00e1s estrictos de las m\u00e1quinas de gran tama\u00f1o.<\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 dir=\"ltr\"><span>La fase de montaje y el control de calidad<\/span><\/h3>\n<p dir=\"ltr\"><span>La fase de <\/span><strong>montaje<\/strong><span>, en la que la <\/span><strong>limpieza<\/strong><span> y la <\/span><strong>repetibilidad<\/strong><span> son requisitos esenciales, es objeto de un cuidado extremo. Antes de ser montados, todos los componentes se lavan por separado y siguen l\u00edneas de flujo espec\u00edficas, diferenciadas por tipo y tama\u00f1o. Cada l\u00ednea est\u00e1 dise\u00f1ada para optimizar sus operaciones individuales, y todos los productos se prueban al 100% en la cadena de fabricaci\u00f3n. Esto garantiza el sellado y el correcto procedimiento de montaje. Una vez ensamblados, los productos avanzan por dos l\u00edneas automatizadas de recubrimiento de superficies, seguidas de las estaciones de paletizaci\u00f3n.&nbsp;<\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p><span><span><span id=\"docs-internal-guid-e27da497-7fff-dee4-7a0a-921670a92ce3\"><span>Antes de ser montados, todos los componentes se lavan por separado y siguen un <\/span><strong>flujo dedicado<\/strong><span> en l\u00edneas diferenciadas por tipo y tama\u00f1o. Cada l\u00ednea ha sido estudiada para optimizar cada una de las operaciones, y todos los productos se <\/span><strong>someten a prueba al 100 % en l\u00ednea<\/strong><span>. Esto garantiza la estanqueidad y el correcto procedimiento de montaje. Una vez ensamblados, los productos prosiguen por las <\/span><strong>dos l\u00edneas de pintura <\/strong><span>automatizadas hasta las estaciones de paletizaci\u00f3n.<\/span><span><br \/><\/span><span><br \/><\/span><span>Por \u00faltimo, el est\u00e1ndar de calidad ITR exigen la realizaci\u00f3n de pruebas, tanto destructivas como no destructivas que incluyen: controles de ultrasonidos, pruebas de dureza, magnaflux, IR, charpy y simulaciones por software de las condiciones de trabajo pesado que act\u00faan sobre los componentes acabados y elementos finitos. A trav\u00e9s de una serie de <\/span><strong>m\u00e1quinas<\/strong><span> desarrolladas expresamente, se pueden probar y desarrollar una gama de nuevos productos para el <\/span><strong>after market<\/strong><span> y <\/span><strong>OEM<\/strong><span> capaces de replicar las condiciones de trabajo m\u00e1s extremas.<\/span><span><br \/><\/span><span><br \/><\/span><span>Gracias a su alta productividad y a la gesti\u00f3n integral del proceso de producci\u00f3n, la planta china representa hoy un polo de excelencia para el suministro de ITR y un centro de referencia para la investigaci\u00f3n y el desarrollo caracterizado por su fuerte orientaci\u00f3n hacia el futuro.<\/span><\/span><\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/zsTJD25gVlo\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<p><span><span><span id=\"docs-internal-guid-9b3b6314-7fff-b209-af61-94d3fdd951f6\"><span>No dejes de seguirnos para saber m\u00e1s en relaci\u00f3n con la planta de ITR Industries situada en Jinju, en Corea del Sur, otro importante centro de producci\u00f3n del Grupo USCO ITR dedicado a la fabricaci\u00f3n de componentes para el tren de rodaje. <\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ITR Industries satisface completamente la demanda del Grupo USCO ITR para la producci\u00f3n de componentes para el tren de rodaje destinados al sector de la posventa y como piezas originales para los m\u00e1s importantes fabricantes de maquinaria de movimiento de tierras.<\/p>\n","protected":false},"author":1,"featured_media":5043,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[133,103],"tags":[],"class_list":["post-9681","post","type-post","status-publish","format-standard","has-post-thumbnail","category-corporativo","category-revista"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITR Industries: centro productivo por excelencia del Grupo USCO ITR - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITR Industries: centro productivo por excelencia del Grupo USCO ITR - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"ITR Industries satisface completamente la demanda del Grupo USCO ITR para la producci\u00f3n de componentes para el tren de rodaje destinados al sector de la posventa y como piezas originales para los m\u00e1s importantes fabricantes de maquinaria de movimiento de tierras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T09:52:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"ITR Industries: centro productivo por excelencia del Grupo USCO ITR\",\"datePublished\":\"2021-10-14T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:52:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/\"},\"wordCount\":1015,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"articleSection\":[\"Corporativo\",\"Revista\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/\",\"name\":\"ITR Industries: centro productivo por excelencia del Grupo USCO ITR - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"datePublished\":\"2021-10-14T00:00:00+00:00\",\"dateModified\":\"2026-09-01T09:52:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITR Industries: centro productivo por excelencia del Grupo USCO ITR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITR Industries: centro productivo por excelencia del Grupo USCO ITR - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/","og_locale":"es_ES","og_type":"article","og_title":"ITR Industries: centro productivo por excelencia del Grupo USCO ITR - ITR WORLD","og_description":"ITR Industries satisface completamente la demanda del Grupo USCO ITR para la producci\u00f3n de componentes para el tren de rodaje destinados al sector de la posventa y como piezas originales para los m\u00e1s importantes fabricantes de maquinaria de movimiento de tierras.","og_url":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2021-10-14T00:00:00+00:00","article_modified_time":"2026-09-01T09:52:42+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assistenza@intersezione.com","Tiempo de lectura":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/es\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"ITR Industries: centro productivo por excelencia del Grupo USCO ITR","datePublished":"2021-10-14T00:00:00+00:00","dateModified":"2026-09-01T09:52:42+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/"},"wordCount":1015,"image":{"@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","articleSection":["Corporativo","Revista"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/","url":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/","name":"ITR Industries: centro productivo por excelencia del Grupo USCO ITR - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","datePublished":"2021-10-14T00:00:00+00:00","dateModified":"2026-09-01T09:52:42+00:00","author":{"@id":"https:\/\/itrworld.com\/es\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/es\/itr-industries-centro-productivo-por-excelencia-del-grupo-usco-itr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"ITR Industries: centro productivo por excelencia del Grupo USCO ITR"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/es\/#website","url":"https:\/\/itrworld.com\/es\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/itrworld.com\/es\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/es\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/posts\/9681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/comments?post=9681"}],"version-history":[{"count":0,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/posts\/9681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/media\/5043"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/media?parent=9681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/categories?post=9681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/tags?post=9681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}