{"id":10125,"date":"2026-03-31T14:43:51","date_gmt":"2026-03-31T14:43:51","guid":{"rendered":"https:\/\/itrworld.com\/exposibram\/"},"modified":"2026-03-31T14:43:51","modified_gmt":"2026-03-31T14:43:51","slug":"exposibram","status":"publish","type":"post","link":"https:\/\/itrworld.com\/es\/exposibram\/","title":{"rendered":"EXPOSIBRAM"},"content":{"rendered":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]August 24-27 | Belo Horizonte, Brazil[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]August 24-27 |&#8230;<\/p>\n","protected":false},"author":2,"featured_media":7432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[104],"tags":[],"class_list":["post-10125","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXPOSIBRAM - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/es\/exposibram\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXPOSIBRAM - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]August 24-27 |...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/es\/exposibram\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T14:43:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"martinamorini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"martinamorini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/\"},\"author\":{\"name\":\"martinamorini\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#\\\/schema\\\/person\\\/f4be2bfeff8b901d1a98044cf351f391\"},\"headline\":\"EXPOSIBRAM\",\"datePublished\":\"2026-03-31T14:43:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/\"},\"wordCount\":188,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/exposibram2026.jpg\",\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/\",\"name\":\"EXPOSIBRAM - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/exposibram2026.jpg\",\"datePublished\":\"2026-03-31T14:43:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#\\\/schema\\\/person\\\/f4be2bfeff8b901d1a98044cf351f391\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/exposibram2026.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/exposibram2026.jpg\",\"width\":541,\"height\":363,\"caption\":\"Exposibram\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/exposibram\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXPOSIBRAM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#\\\/schema\\\/person\\\/f4be2bfeff8b901d1a98044cf351f391\",\"name\":\"martinamorini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63656566b322ef274b38c504ac0af5ecdb4ccf510462862ca09a812e95d1a613?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63656566b322ef274b38c504ac0af5ecdb4ccf510462862ca09a812e95d1a613?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63656566b322ef274b38c504ac0af5ecdb4ccf510462862ca09a812e95d1a613?s=96&d=mm&r=g\",\"caption\":\"martinamorini\"},\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/author\\\/martinamorini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXPOSIBRAM - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/es\/exposibram\/","og_locale":"es_ES","og_type":"article","og_title":"EXPOSIBRAM - ITR WORLD","og_description":"[vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]August 24-27 |...","og_url":"https:\/\/itrworld.com\/es\/exposibram\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2026-03-31T14:43:51+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg","type":"image\/jpeg"}],"author":"martinamorini","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"martinamorini","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/es\/exposibram\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/es\/exposibram\/"},"author":{"name":"martinamorini","@id":"https:\/\/itrworld.com\/es\/#\/schema\/person\/f4be2bfeff8b901d1a98044cf351f391"},"headline":"EXPOSIBRAM","datePublished":"2026-03-31T14:43:51+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/es\/exposibram\/"},"wordCount":188,"image":{"@id":"https:\/\/itrworld.com\/es\/exposibram\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/03\/exposibram2026.jpg","articleSection":["Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/es\/exposibram\/","url":"https:\/\/itrworld.com\/es\/exposibram\/","name":"EXPOSIBRAM - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/es\/exposibram\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/es\/exposibram\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/03\/exposibram2026.jpg","datePublished":"2026-03-31T14:43:51+00:00","author":{"@id":"https:\/\/itrworld.com\/es\/#\/schema\/person\/f4be2bfeff8b901d1a98044cf351f391"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/es\/exposibram\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/es\/exposibram\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/itrworld.com\/es\/exposibram\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/03\/exposibram2026.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/03\/exposibram2026.jpg","width":541,"height":363,"caption":"Exposibram"},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/es\/exposibram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"EXPOSIBRAM"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/es\/#website","url":"https:\/\/itrworld.com\/es\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/itrworld.com\/es\/#\/schema\/person\/f4be2bfeff8b901d1a98044cf351f391","name":"martinamorini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/63656566b322ef274b38c504ac0af5ecdb4ccf510462862ca09a812e95d1a613?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/63656566b322ef274b38c504ac0af5ecdb4ccf510462862ca09a812e95d1a613?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63656566b322ef274b38c504ac0af5ecdb4ccf510462862ca09a812e95d1a613?s=96&d=mm&r=g","caption":"martinamorini"},"url":"https:\/\/itrworld.com\/es\/author\/martinamorini\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/posts\/10125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/comments?post=10125"}],"version-history":[{"count":0,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/posts\/10125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/media\/7432"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/media?parent=10125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/categories?post=10125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/tags?post=10125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}