{"id":8800,"date":"2025-10-10T12:46:32","date_gmt":"2025-10-10T12:46:32","guid":{"rendered":"https:\/\/itrworld.com\/?page_id=8800"},"modified":"2026-06-29T12:44:58","modified_gmt":"2026-06-29T12:44:58","slug":"oportunidades-profesionales","status":"publish","type":"page","link":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/","title":{"rendered":"Oportunidades profesionales"},"content":{"rendered":"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#E5E5E5&#8243; bg_image=\u00bb2083&#8243; background_image_preload=\u00bbtrue\u00bb bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbcenter center\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb100&#8243; bottom_padding=\u00bb50&#8243; left_padding_desktop=\u00bb25px\u00bb left_padding_tablet=\u00bb2%\u00bb constrain_group_4=\u00bbyes\u00bb right_padding_tablet=\u00bb2%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb class=\u00bbforce_gradient\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0A000036&#8243; color_overlay_2=\u00bb#000000&#8243; overlay_strength=\u00bb0.95&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb height_desktop=\u00bb500&#8243; height_tablet=\u00bb600&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner left_padding_desktop=\u00bb50px\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbadvanced\u00bb gradient_type=\u00bbdefault\u00bb][nectar_highlighted_text scribble_color=\u00bb#DC0813&#8243; style=\u00bbscribble\u00bb scribble_shape=\u00bbbasic-underline\u00bb scribble_thickness=\u00bbregular\u00bb scribble_speed=\u00bb0s\u00bb scribble_easing=\u00bbease_in_out\u00bb disable_mobile_animation=\u00bbtrue\u00bb custom_font_size=\u00bb4vw\u00bb font_size_tablet=\u00bb7vw\u00bb font_line_height=\u00bb1.1em\u00bb text_direction=\u00bbdefault\u00bb]\n<h1><em>Oportunidades profesionales<\/em><\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbright\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/2&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb50&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css=\u00bb.vc_custom_1782737078221{margin-bottom: 20px !important;}\u00bb text_direction=\u00bbdefault\u00bb]\n<h4>\u00danete a un entorno internacional en el que confluyen culturas distintas para crear valor.<\/h4>\n<p>Creemos en la pasi\u00f3n, el respeto y el crecimiento profesional: principios que gu\u00edan nuestra forma de trabajar en equipo.<\/p>\n<p>Descubre nuestros puestos vacantes en todo el mundo o env\u00eda tu propuesta espont\u00e1nea para entrar a formar parte de nuestra organizaci\u00f3n.[\/vc_column_text][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb bottom_padding=\u00bb0&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][vc_column column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbmedium_depth\u00bb column_border_radius=\u00bb15px\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb2\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb content_layout=\u00bbdefault\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<div class=\"col-sm-12\">\n<div class=\"title\">\n<h3><span style=\"color: #ff0000;\">Env\u00edanos tu solicitud<\/span><\/h3>\n<\/div>\n<\/div>\n[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9014-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"9014\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/8800#wpcf7-f9014-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9014\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9014-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:9014,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;}}\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> Tu nombre<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Tu correo electr\u00f3nico<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Tu tel\u00e9fono<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-571\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-571\" \/><\/span> <\/label>\n<\/p>\n<p><label>Puesto de trabajo<\/label>\n<\/p>\n<p><select name=\"posizione\" id=\"cf7-posizione-select\">\n\n <option value=\"\">Cargando\u2026<\/option>\n\n<\/select>\n<\/p>\n<p><label>Curriculum Vitae<\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"file-932\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".pdf,.doc,.docx,.odt,.rtf,.txt\" aria-invalid=\"false\" type=\"file\" name=\"file-932\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"Privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Declaro que he le\u00eddo la <a href=\"\/privacy\" target=\"_blank\">pol\u00edtica de privacidad<\/a> y autorizo el tratamiento de mis datos personales.*<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/6&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#F5F5F7&#8243; scene_position=\u00bbcenter\u00bb top_padding=\u00bb75&#8243; constrain_group_1=\u00bbyes\u00bb bottom_padding=\u00bb75&#8243; text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_post_grid post_type=\u00bbcustom\u00bb cpt_name=\u00bbposizione\u00bb order=\u00bbDESC\u00bb orderby=\u00bbdate\u00bb pagination=\u00bbnone\u00bb columns=\u00bb1&#8243; columns_tablet=\u00bbdefault\u00bb columns_phone=\u00bbdefault\u00bb grid_item_spacing=\u00bb15px\u00bb image_size=\u00bblarge\u00bb aspect_ratio_image_size=\u00bbyes\u00bb custom_image_aspect_ratio=\u00bb16-9&#8243; content_next_to_image_image_width=\u00bb33.3%\u00bb content_next_to_image_image_gap=\u00bbdefault\u00bb content_next_to_image_image_position=\u00bbleft\u00bb image_loading=\u00bbdefault\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_stagger=\u00bb90&#8243; animation_easing=\u00bbdefault\u00bb heading_tag=\u00bbdefault\u00bb heading_tag_render=\u00bbspan\u00bb category_position=\u00bbdefault\u00bb display_excerpt=\u00bbyes\u00bb content_next_to_image_excerpt_pos=\u00bbdefault\u00bb excerpt_display=\u00bbdefault\u00bb additional_meta_size=\u00bbdefault\u00bb custom_fields_location=\u00bbbefore_post_meta\u00bb custom_fields=\u00bb%5B%7B%22meta_key%22%3A%22city%22%2C%22use_custom_format%22%3A%22%22%2C%22custom_format%22%3A%22City%3A%20%3Cb%3E%25s%3C%2Fb%3E%22%2C%22render_tag%22%3A%22span%22%7D%2C%7B%22meta_key%22%3A%22hours%22%2C%22use_custom_format%22%3A%22%22%2C%22custom_format%22%3A%22%20-%20Hours%3A%20%3Cb%3E%25s%3C%2Fb%3E%22%2C%22render_tag%22%3A%22span%22%7D%2C%7B%22meta_key%22%3A%22pay%22%2C%22use_custom_format%22%3A%22%22%2C%22custom_format%22%3A%22%20-%20Pay%3A%20%3Cb%3E%25s%3C%2Fb%3E%22%2C%22render_tag%22%3A%22span%22%7D%2C%7B%22meta_key%22%3A%22site%22%2C%22use_custom_format%22%3A%22%22%2C%22custom_format%22%3A%22%3Cspan%3E%25s%3C%2Fspan%3E%22%2C%22render_tag%22%3A%22p%22%7D%5D\u00bb grid_style=\u00bbcontent_next_to_image\u00bb text_color=\u00bbdark\u00bb content_next_to_image_vertical_align=\u00bbmiddle\u00bb hover_effect=\u00bbslow_zoom\u00bb border_radius=\u00bb10px\u00bb display_type=\u00bbgrid\u00bb custom_font_size=\u00bb24&#8243; excerpt_length=\u00bb40&#8243; font_line_height=\u00bb1.2&#8243; css_class_name=\u00bbjobs\u00bb][\/vc_column][\/vc_row][vc_row type=\u00bbin_container\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb scene_position=\u00bbcenter\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.3&#8243; gradient_direction=\u00bbleft_to_right\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#E5E5E5&#8243; bg_image=\u00bb2083&#8243; background_image_preload=\u00bbtrue\u00bb bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbcenter center\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb100&#8243; bottom_padding=\u00bb50&#8243; left_padding_desktop=\u00bb25px\u00bb left_padding_tablet=\u00bb2%\u00bb constrain_group_4=\u00bbyes\u00bb right_padding_tablet=\u00bb2%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb class=\u00bbforce_gradient\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0A000036&#8243; color_overlay_2=\u00bb#000000&#8243; overlay_strength=\u00bb0.95&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb height_desktop=\u00bb500&#8243; height_tablet=\u00bb600&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"page_category":[],"page_tag":[],"class_list":["post-8800","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Oportunidades profesionales - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oportunidades profesionales - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#E5E5E5&#8243; bg_image=\u00bb2083&#8243; background_image_preload=\u00bbtrue\u00bb bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbcenter center\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb100&#8243; bottom_padding=\u00bb50&#8243; left_padding_desktop=\u00bb25px\u00bb left_padding_tablet=\u00bb2%\u00bb constrain_group_4=\u00bbyes\u00bb right_padding_tablet=\u00bb2%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb class=\u00bbforce_gradient\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0A000036&#8243; color_overlay_2=\u00bb#000000&#8243; overlay_strength=\u00bb0.95&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb height_desktop=\u00bb500&#8243; height_tablet=\u00bb600&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T12:44:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/oportunidades-profesionales\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/oportunidades-profesionales\\\/\",\"name\":\"Oportunidades profesionales - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#website\"},\"datePublished\":\"2025-10-10T12:46:32+00:00\",\"dateModified\":\"2026-06-29T12:44:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/oportunidades-profesionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/es\\\/oportunidades-profesionales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/oportunidades-profesionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oportunidades profesionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/es\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oportunidades profesionales - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/","og_locale":"es_ES","og_type":"article","og_title":"Oportunidades profesionales - ITR WORLD","og_description":"[vc_row type=\u00bbfull_width_content\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bbdefault\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbbottom\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#E5E5E5&#8243; bg_image=\u00bb2083&#8243; background_image_preload=\u00bbtrue\u00bb bg_image_type=\u00bbdefault\u00bb bg_position=\u00bbcenter center\u00bb background_image_loading=\u00bbdefault\u00bb bg_repeat=\u00bbno-repeat\u00bb scene_position=\u00bbcenter\u00bb top_padding=\u00bb100&#8243; bottom_padding=\u00bb50&#8243; left_padding_desktop=\u00bb25px\u00bb left_padding_tablet=\u00bb2%\u00bb constrain_group_4=\u00bbyes\u00bb right_padding_tablet=\u00bb2%\u00bb text_color=\u00bblight\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb row_position_desktop=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb class=\u00bbforce_gradient\u00bb enable_gradient=\u00bbtrue\u00bb color_overlay=\u00bb#0A000036&#8243; color_overlay_2=\u00bb#000000&#8243; overlay_strength=\u00bb0.95&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb gradient_type=\u00bbdefault\u00bb shape_type=\u00bb\u00bb height_desktop=\u00bb500&#8243; height_tablet=\u00bb600&#8243;][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb flex_gap_desktop=\u00bb10px\u00bb column_element_direction_desktop=\u00bbdefault\u00bb...","og_url":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_modified_time":"2026-06-29T12:44:58+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/","url":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/","name":"Oportunidades profesionales - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/es\/#website"},"datePublished":"2025-10-10T12:46:32+00:00","dateModified":"2026-06-29T12:44:58+00:00","breadcrumb":{"@id":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/es\/oportunidades-profesionales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/es\/oportunidades-profesionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/es\/"},{"@type":"ListItem","position":2,"name":"Oportunidades profesionales"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/es\/#website","url":"https:\/\/itrworld.com\/es\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/pages\/8800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/comments?post=8800"}],"version-history":[{"count":2,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/pages\/8800\/revisions"}],"predecessor-version":[{"id":8813,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/pages\/8800\/revisions\/8813"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/media?parent=8800"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/page_category?post=8800"},{"taxonomy":"page_tag","embeddable":true,"href":"https:\/\/itrworld.com\/es\/wp-json\/wp\/v2\/page_tag?post=8800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}