{"id":4668,"date":"2021-10-14T00:00:00","date_gmt":"2021-10-14T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/"},"modified":"2026-09-01T10:26:13","modified_gmt":"2026-09-01T10:26:13","slug":"itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr","status":"publish","type":"post","link":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/","title":{"rendered":"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR"},"content":{"rendered":"<h2>ITR Industries produziert den kompletten Bedarf an Laufwerkskomponenten der Unternehmensgruppe USCO ITR. ITR Industries produziert sowohl die Bedarfe an Laufwerkskomponenten f\u00fcr den Ersatzteilmarkt als auch f\u00fcr die Erstausr\u00fcstung. Zu den Kunden im Bereich der Erstausr\u00fcstung geh\u00f6ren die wichtigsten Hersteller im Bereich der erdbewegenden Industrie. \u00a0<\/h2>\n<h4>Im Zentrum der ITR-Lieferkette steht neben ITR Meccanica, dem Produktionszentrum des Gesch\u00e4ftsbereichs \u201eSonstiges\u201c, ITR Industries. ITR Industries verf\u00fcgt \u00fcber zwei Fertigungsstandorte: Im Werk in S\u00fcdkorea werden Laufwerksketten, Bodenplatten, geschmiedete Turas-Segmente, Trag- und Laufrollen gefertigt. Im Werk in China werden Trag- und Laufrollen, Leitr\u00e4der und gegossene Turas hergestellt. In diesem Artikel sprechen wir \u00fcber den chinesischen Produktionsstandort.<\/h4>\n<p dir=\"ltr\"><span>Mit seinem in Yantai, im Herzen von Shandong, gelegenen Werk, profitiert das Unternehmen von einer <\/span><span>strategischen Position, um Modena und die anderen ITR-Niederlassungen auf der ganzen Welt zu beliefern<\/span><span>. Das Werk verf\u00fcgt \u00fcber eine <\/span><span>54.000 m\u00b2 gro\u00dfe Werksfl\u00e4che, von der 29.000 m\u00b2 \u00fcberdacht sind. <\/span><span>Es liegt in einer chinesischen Region, die f\u00fcr ihre \u00fcberzeugenden Leistungen im Automobilsektor und in der Pr\u00e4zisionselektronik bekannt ist: General Motors\u00ae, Hyundai\u00ae, Apple\u00ae und LG\u00ae sind nur einige der Marken, die hier bedeutende Produktionsstandorte haben.&nbsp;<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Es handelt sich um ein konsolidiertes Produktionswerk, dessen Fertigungskapazit\u00e4ten st\u00e4ndig erweitert und ausgebaut werden. In letzter Zeit wurden vor allem Investitionen im Bereich Umweltschutz get\u00e4tigt. Durch diese Investitionen werden die aktuellen und sehr restriktiven Umweltstandards erf\u00fcllt. Gleichzeitig wurde die Gelegenheit genutzt, um Produktionsprozesse zu hinterfragen und die Lean-Management Philosophie umzusetzen. Dadurch werden Gesch\u00e4ftsprozesse stetig verbessert und Verschwendung weiter reduziert.<\/span><\/p>\n<p><span id=\"docs-internal-guid-d2698151-7fff-85cd-d5bb-21b33c1dbe90\"><span>Die Gie\u00dferei wurde nach dem <\/span><span>Materialfluss-Prinzip<\/span><span> neu entworfen und die Transportprozesse der Gussformen automatisiert. Durch die neuen Anlagen in der Gie\u00dferei ist ITR Industries China bereits heute auf die Herausforderungen der n\u00e4chsten Jahrzehnte zur weiteren Reduzierung der <\/span><span>Emissionen<\/span><span> bestens vorbereitet.<\/span><\/span><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/wvs-hFooXOQ?si=bLEqJUGA9c426-Ir\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<h3><span><span id=\"docs-internal-guid-32571e21-7fff-b5b5-4b3b-1458e5441932\"><span>Vollst\u00e4ndige Kontrolle \u00fcber die Fertigung von Trag- und Laufrollen, Turas und Leitr\u00e4dern<\/span><\/span><\/span><\/h3>\n<p dir=\"ltr\"><span>Das chinesische Unternehmen stellt vor allem <\/span><span>Lauf-<\/span><span> und <\/span><span>Tragrollen<\/span><span>, <\/span><span>gegossene Turas<\/span><span> und <\/span><span>Leitr\u00e4der<\/span><span> f\u00fcr Raupenfahrwerke her. Die hier gefertigten Komponenten entsprechen in allen Aspekten den Anforderungen der Unternehmensgruppe USCO ITR und machen ITR Industries zu einer wichtigen Drehscheibe f\u00fcr die ITR-Lieferkette im Fahrwerksbereich.<\/span><span><br \/><\/span><span><br \/><\/span><span>Der Fertigungsprozess von gegossenen Turas und Leitr\u00e4dern beginnt direkt mit der Verarbeitung des Rohmaterials. Die werkseigenen Schmelz\u00f6fen garantieren eine gro\u00dfe <\/span><span>Autonomie f\u00fcr das Unternehmen<\/span><span> und eine hohe Verarbeitungsqualit\u00e4t. Die Produktion setzt sich dann mit mechanischen CNC-Bearbeitungsb\u00e4nken und W\u00e4rmebehandlungen fort und die Komponenten werden zu den Montage- und Lackierstationen weitertransportiert. Um die kontinuierliche Verbesserung voranzutreiben wurden auch diese Abteilungen erst k\u00fcrzlich <\/span><span>neugestaltet<\/span><span>. Dabei widmen sich spezielle Teams der stetigen Reduzierung von <\/span><span>Ausschuss<\/span><span>. Die neue Struktur zielt besonders darauf ab, die sogenannten sieben MUDA zu begrenzen: Die Verschwendung in Bezug auf Wartezeiten, Transport, \u00dcberbest\u00e4nde, Handhabung, M\u00e4ngel und das Vorhandensein von \u201enutzlosen\u201c Vorg\u00e4ngen im Verarbeitungsprozess.<\/span><span><\/p>\n<p><\/span><\/p>\n<p><span><span><span><span id=\"docs-internal-guid-c3a6ca80-7fff-0be8-3d79-0891f6082ecc\"><span>Die <\/span><span>Trag-<\/span><span> und <\/span><span>Laufrollen<\/span><span> werden direkt aus geschmiedeten Stahllegierungen gewonnen. Diese werden dann mechanisch bearbeitet. Um die richtigen <\/span><span>Eigenschaften<\/span><span> bez\u00fcglich Verschlei\u00dffestigkeit und Standfestigkeit zu erhalten, werden die Komponenten einer W\u00e4rmebehandlung unterzogen. Einige der j\u00fcngsten Investitionen zielten vor allem darauf ab, die Leistung der <\/span><span>W\u00e4rmebehandlung<\/span><span>, der Kern des <\/span><span>Know-hows<\/span><span> von ITR, weiter zu verbessern. Damit wird nun auch die Erf\u00fcllung der immer anspruchsvolleren Standards von Gro\u00dfmaschinen gew\u00e4hrleistet.<\/span><\/span><\/span><\/span><\/span><\/p>\n<h3><span id=\"docs-internal-guid-30325cd7-7fff-37b7-8c70-2a9b0198d954\"><span>Die Montage- und Qualit\u00e4tskontrollphasen<\/span><\/span><\/h3>\n<p dir=\"ltr\"><span>Besonderes Augenmerk wird auf die <\/span><span>Montagephase<\/span><span> gelegt, in der <\/span><span>Reinheit<\/span><span> und <\/span><span>Wiederholbarkeit<\/span><span> wesentliche Elemente sind. Vor dem Zusammenbau werden alle Komponenten einzeln gereinigt und folgen einem <\/span><span>definierten Materialfluss<\/span><span> auf nach Typ und Gr\u00f6\u00dfe getrennten Fertigungsstra\u00dfen. Jede Fertigungsstra\u00dfe wurde unter dem Gesichtspunkt der Optimierung entwickelt. Alle Produkte werden <\/span><span>zu 100 % in der jeweiligen Fertigungsstra\u00dfe getestet. <\/span><span>Dies garantiert ein korrektes Montageverfahren, Wiederholbarkeit und top Produktqualit\u00e4t. Nach der Montage geht es weiter auf den <\/span><span>beiden automatisierten Lackierstra\u00dfen<\/span><span> bis zu den Palettierstationen.<\/span><span><br \/><\/span><span><br \/><\/span><span>Schlie\u00dflich sieht der ITR-Qualit\u00e4tsstandard sowohl destruktive als auch nicht destruktive <\/span><span>\u00dcberpr\u00fcfungen<\/span><span> vor. Dazu geh\u00f6ren: Ultraschallpr\u00fcfungen, H\u00e4rtepr\u00fcfungen, Magnaflux, IR, Charpy und Rollpr\u00fcfst\u00e4nde. Zur Auslegung der Produkte in einem fr\u00fchen Stadium der Produktentwicklung erfolgt die Simulation rauer Arbeitsbedingungen unter Einsatz von Software-Modellen und Finite Elemente Analysen. Durch eine Reihe speziell entwickelter <\/span><span>Maschinen<\/span><span> ist es m\u00f6glich, neue Produkte f\u00fcr den <\/span><span>Ersatzteil- <\/span><span>und <\/span><span>Erstmontagemarkt<\/span><span> zu entwickeln und zu testen, die h\u00e4rtesten Arbeitsbedingungen standhalten.<\/span><span><br \/><\/span><span><br \/><\/span><span>Dank seiner Produktivit\u00e4t und der kompletten Steuerung s\u00e4mtlicher Fertigungsverfahren ist das chinesische Werk heute ein Kompetenzzentrum f\u00fcr ITR-Lieferungen und ein Referenzzentrum f\u00fcr <\/span><span>Forschung und Entwicklung<\/span><span>. Stetige Investitionen in das Produktionswerk sichern auch in Zukunft seine herausragende Stellung in der USCO ITR Gruppe.<\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/zsTJD25gVlo\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p dir=\"ltr\"><span>Folgen Sie uns weiterhin, um mehr \u00fcber den Hauptsitz von ITR Industries in Jinju in S\u00fcdkorea zu erfahren. Ein weiteres wichtiges Produktionszentrum zur Produktion von Fahrwerkskomponenten der Unternehmensgruppe USCO ITR.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ITR Industries produziert den kompletten Bedarf an Laufwerkskomponenten der Unternehmensgruppe USCO ITR. ITR Industries produziert sowohl die Bedarfe an Laufwerkskomponenten f\u00fcr den Ersatzteilmarkt als auch f\u00fcr die Erstausr\u00fcstung. Zu den Kunden im Bereich der Erstausr\u00fcstung geh\u00f6ren die wichtigsten Hersteller im Bereich der erdbewegenden Industrie. \u00a0<\/p>\n","protected":false},"author":1,"featured_media":5043,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[118,130],"tags":[],"class_list":["post-4668","post","type-post","status-publish","format-standard","has-post-thumbnail","category-magazin","category-unternehmen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"ITR Industries produziert den kompletten Bedarf an Laufwerkskomponenten der Unternehmensgruppe USCO ITR. ITR Industries produziert sowohl die Bedarfe an Laufwerkskomponenten f\u00fcr den Ersatzteilmarkt als auch f\u00fcr die Erstausr\u00fcstung. Zu den Kunden im Bereich der Erstausr\u00fcstung geh\u00f6ren die wichtigsten Hersteller im Bereich der erdbewegenden Industrie. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:26:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR\",\"datePublished\":\"2021-10-14T00:00:00+00:00\",\"dateModified\":\"2026-09-01T10:26:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/\"},\"wordCount\":803,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"articleSection\":[\"Magazin\",\"Unternehmen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/\",\"name\":\"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"datePublished\":\"2021-10-14T00:00:00+00:00\",\"dateModified\":\"2026-09-01T10:26:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/itr-agri-magazine.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/","og_locale":"de_DE","og_type":"article","og_title":"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR - ITR WORLD","og_description":"ITR Industries produziert den kompletten Bedarf an Laufwerkskomponenten der Unternehmensgruppe USCO ITR. ITR Industries produziert sowohl die Bedarfe an Laufwerkskomponenten f\u00fcr den Ersatzteilmarkt als auch f\u00fcr die Erstausr\u00fcstung. Zu den Kunden im Bereich der Erstausr\u00fcstung geh\u00f6ren die wichtigsten Hersteller im Bereich der erdbewegenden Industrie. \u00a0","og_url":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2021-10-14T00:00:00+00:00","article_modified_time":"2026-09-01T10:26:13+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"assistenza@intersezione.com","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/de\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR","datePublished":"2021-10-14T00:00:00+00:00","dateModified":"2026-09-01T10:26:13+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/"},"wordCount":803,"image":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","articleSection":["Magazin","Unternehmen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/","url":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/","name":"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","datePublished":"2021-10-14T00:00:00+00:00","dateModified":"2026-09-01T10:26:13+00:00","author":{"@id":"https:\/\/itrworld.com\/de\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/itr-agri-magazine.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/de\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/de\/"},{"@type":"ListItem","position":2,"name":"ITR Industries: Herausragendes Produktionszentrum der Unternehmensgruppe USCO ITR"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/de\/#website","url":"https:\/\/itrworld.com\/de\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/itrworld.com\/de\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/de\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts\/4668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/comments?post=4668"}],"version-history":[{"count":1,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts\/4668\/revisions"}],"predecessor-version":[{"id":10213,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts\/4668\/revisions\/10213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/media\/5043"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/media?parent=4668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/categories?post=4668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/tags?post=4668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}