{"id":4659,"date":"2022-02-03T00:00:00","date_gmt":"2022-02-03T00:00:00","guid":{"rendered":"https:\/\/itrworld.com\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/"},"modified":"2026-09-01T10:26:11","modified_gmt":"2026-09-01T10:26:11","slug":"itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr","status":"publish","type":"post","link":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/","title":{"rendered":"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR"},"content":{"rendered":"<h2>Das Herzst\u00fcck der Lieferkette von USCO ITR f\u00fcr den Fahrwerksbau ist ITR Industries mit seinen Niederlassungen in China und S\u00fcdkorea.<\/h2>\n<h4>W\u00e4hrend wir im vorherigen Artikel \u00fcber das chinesische Werk gesprochen haben, steht in diesem Artikel das koreanische Unternehmen im Mittelpunkt, ein hochmodernes Fertigungszentrum, das sich auf Ketten, Bodenplatten, Segmente und Rollen spezialisiert hat.<\/h4>\n<p dir=\"ltr\"><span>Die <\/span><strong>koreanischen Fabriken von ITR Industries <\/strong><span>verteilen sich \u00fcber insgesamt <\/span><strong>63.000 m<sup>2<\/sup><\/strong><span> und liegen in einer strategischen Position, um Modena und alle anderen ITR-Niederlassungen erreichen und beliefern zu k\u00f6nnen. Am meisten befinden sie sich in <\/span><span>Jinju<\/span><span> in der N\u00e4he von Busan, einem der gr\u00f6\u00dften Seeh\u00e4fen der Welt.&nbsp;<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>ITR Industries Korea ist ein konsolidiertes und kontinuierlich wachsendes Industrieunternehmen, das im Hinblick auf eine kontinuierliche Verbesserung an einer fortschreitenden Weiterentwicklung seiner Werke arbeitet, wie die Er\u00f6ffnung eines neuen Standorts f\u00fcr die Herstellung von Rollen im Jahr 2021 zeigt.<\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Industries-Jinju-South-Korea.jpg\" alt=\"ITR Industries Korea\" width=\"724\" height=\"342\"><\/p>\n<p dir=\"ltr\"><span id=\"docs-internal-guid-bd31622d-7fff-770e-0cc5-03462946d8a1\"><span id=\"docs-internal-guid-aa198ef2-7fff-9843-3c90-f0945943db1d\"><span>Die Fabrik in Jinju konzentriert sich vor allem auf die Herstellung von <\/span><strong>Ketten, Bodenplatten, Segmenten und Rollen <\/strong><span>f\u00fcr Fahrwerke. Was die <\/span><strong>Fertigungsverfahren angeht<\/strong><span>, befinden sich hier Formanlagen, mechanische Bearbeitungs- und W\u00e4rmebehandlungsstra\u00dfen und die vollst\u00e4ndige \u00dcberwachung der Kettenmontagevorg\u00e4nge.<\/span><\/span><\/span><\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/9srXNuDS608?si=4djDoKMAwlutfgZH\" width=\"560\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<h3 dir=\"ltr\"><span id=\"docs-internal-guid-e9fa55d3-7fff-b053-92dc-44be1afe6a2c\"><span>Die Formteile<\/span><\/span><\/h3>\n<p dir=\"ltr\"><span>Bei der Herstellung von Ketten, Segmenten und Halbrollen kann nur die Qualit\u00e4t der geschmiedeten Komponenten die <strong>ITR-<\/strong><\/span><strong>Standards<\/strong><span> garantieren.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><strong>Die Formanlage befindet sich in Sacheon<\/strong><span>, nur wenige Kilometer von Jinju entfernt. Hier werden Kettenglieder, Buchsen, Segmente und Halbrollen gefertigt: alles strategische Komponenten, um die <\/span><strong>Produktionsautonomie<\/strong><span> des Unternehmens und eine <\/span><span>hohe <strong>Verarbeitungsqualit\u00e4t<\/strong><\/span><span> zu sichern.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Das <\/span><strong>Verfahren<\/strong><span> beginnt mit einem Barren aus einer Stahllegierung. Diese wird zugeschnitten, dann \u00fcber Induktion erhitzt, geschmiedet und w\u00e4rmebehandelt.&nbsp;<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span id=\"docs-internal-guid-bc4fca67-7fff-fbaf-f727-f312010569d8\"><span>In den letzten Jahren wurde bei den Formanlagen viel in die <\/span><strong>Automatisierung<\/strong><span> durch den Einsatz von <\/span><strong>anthropomorphen Robotern&nbsp;investiert<\/strong><span> und die Abl\u00e4ufe wurden entsprechend neu ausgerichtet. Qualit\u00e4t und Effizienz sind die Eckpfeiler dieses Fertigungsverfahrens. Es ist kein Zufall, dass ITR Industries schon immer auf die <\/span><strong>Reduzierung von Verschwendung<\/strong><span> gedr\u00e4ngt hat: Alles \u00dcberfl\u00fcssige muss eliminiert werden, und nur der Mehrwert f\u00fcr den Kunden darf im Mittelpunkt stehen.<\/span><\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<h3 dir=\"ltr\"><span id=\"docs-internal-guid-a8c1ea1f-7fff-1fab-91e4-00fd8ac5adc7\"><span>Mechanische Bearbeitung und W\u00e4rmebehandlung<\/span><\/span><\/h3>\n<p dir=\"ltr\"><span>Sobald die Grundkomponenten hergestellt sind, geht es f\u00fcr die verschiedenen Details nach Jinju zur\u00fcck. Hier werden sie von CNC-Batterien mechanisch bearbeitet und <\/span><strong>W\u00e4rmebehandlungen<\/strong><span> unterzogen. Die installierte Maschinen garantieren eine kontinuierliche Versorgung mit allen Komponenten und bef\u00f6rdern diese zu den <\/span><strong>Montagestationen<\/strong><span> oder zum Versand (bei Ersatzteilen).<\/span><\/p>\n<p dir=\"ltr\"><span id=\"docs-internal-guid-22d03c69-7fff-5b10-18d4-e31e8a270c80\"><br \/><span>Nicht nur Glieder, Stifte und Buchsen: auch die <\/span><strong>Bodenplatten<\/strong><span> werden im Haus hergestellt In diesem Fall wird von einem Formprofil ausgegangen, das geschnitten und w\u00e4rmebehandelt wird, um die fertige Bodenplatte zu erhalten. All das geschieht in einer <\/span><strong>einzigen Fertigungsstra\u00dfe<\/strong><span>.<\/span><\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<h3 dir=\"ltr\"><span id=\"docs-internal-guid-4f813d3a-7fff-3afc-ef6b-8e42cc58d300\"><span>Vollst\u00e4ndige \u00dcberwachung der Kettenmontagevorg\u00e4nge<\/span><\/span><\/h3>\n<p dir=\"ltr\"><span>Wie im <\/span><a href=\"\/de\/itr-magazine\/itr-industries-herausragendes-produktionszentrum-der-unternehmensgruppe-usco-itr-2021\/\" target=\"_blank\"><strong>chinesischen Werk in Yantai<\/strong><\/a><span> wird auch der Montagephase in <\/span><span>Korea<\/span><span> gr\u00f6\u00dfte Aufmerksamkeit geschenkt. Reinheit und Widerholbarkeit sind grundlegende Elemente, und die Komponenten folgen einem bestimmten <\/span><strong>Verlauf auf den Produktionsstra\u00dfen<\/strong><span>, unterteilt nach Typ und Gr\u00f6\u00dfe.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Jede Fertigungsstra\u00dfe ist darauf ausgelegt, die einzelne Arbeitsg\u00e4nge zu <\/span><span>optimieren<\/span><span>. Dar\u00fcber hinaus werden alle Produkte <\/span><strong>in der Anlage getestet<\/strong><span>, um einen ordnungsgem\u00e4\u00dfen Montagevorgang sicherzustellen. Nach der Montage werden sie weiter zum Lackierbereich und dann zum Versandbereich bef\u00f6rdert.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span><span>Der ITR-Qualit\u00e4tsstandard sieht sowohl destruktive als auch nicht destruktive <\/span><strong>\u00dcberpr\u00fcfungen<\/strong><span> vor. Dazu geh\u00f6ren: <\/span><span><br \/><\/span><span><br \/><\/span><\/span><\/p>\n<ul>\n<li><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span>Ultraschallpr\u00fcfungen<\/span><\/span><\/li>\n<li><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span>H\u00e4rtepr\u00fcfungen<\/span><\/span><\/li>\n<li><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span>Magnaflux<\/span><\/span><\/li>\n<li><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span>IR<\/span><\/span><\/li>\n<li><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span>Charpy<\/span><\/span><\/li>\n<li><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span>Simulation rauer Arbeitsbedingungen unter Einsatz von Software und fertigen Elementen. <\/span><\/span><\/li>\n<\/ul>\n<p dir=\"ltr\"><span id=\"docs-internal-guid-71c55785-7fff-7e9d-734e-dd9b4c5bbaea\"><span><br \/><\/span><span>Durch eine Reihe speziell entwickelter <\/span><strong>Maschinen<\/strong><span> ist es dar\u00fcber hinaus m\u00f6glich, eine Reihe neuer Produkte f\u00fcr den <\/span><strong>Verbrauchermarkt und OEMs<\/strong><span> zu testen und zu entwickeln, die h\u00e4rtesten Arbeitsbedingungen gerecht werden<\/span><\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<h3 dir=\"ltr\"><span id=\"docs-internal-guid-37187d45-7fff-8410-bcc5-28d03d262397\"><span>Standards aus dem Automobilbau im Dienste des Fahrwerks: die neue Fabrik f\u00fcr die Rollenfertigung<\/span><\/span><\/h3>\n<p dir=\"ltr\"><span id=\"docs-internal-guid-c8ee05de-7fff-e244-4f6e-2d37bd0c2029\"><span>Wie zu Beginn des Artikels erw\u00e4hnt, wurde 2021 eine Neuheit bei ITR Industries: die Inbetriebnahme einer <\/span><strong>neuen Rollenfabrik<\/strong><span> in der N\u00e4he des koreanischen ITR-Werks. Diese hochmoderne Produktionseinheit folgt den f\u00fcr den Automobilbau typischen <\/span><strong>bew\u00e4hrten Verfahren<\/strong><span>, bei denen Qualit\u00e4t, p\u00fcnktliche Lieferung und Effizienz die Eckpfeiler des Gesch\u00e4fts darstellen.<\/span><\/span><\/p>\n<p dir=\"ltr\">&nbsp;<\/p>\n<\/p>\n<div class=\"ri\"><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/ugw8ksnmzpY\" width=\"600\" height=\"315\" frameborder=\"0\"><\/iframe><\/div>\n<p dir=\"ltr\">&nbsp;<\/p>\n<p dir=\"ltr\"><span>Die Unternehmensgruppe strebt eine zunehmende Diversifizierung der Bezugsquellen an, um <\/span><strong>h\u00f6chste Qualit\u00e4tsstandards<\/strong><span> und eine <\/span><strong>flexible Lieferkette<\/strong><span> zu gew\u00e4hrleisten, die allen Marktbedingungen gerecht wird.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Die <\/span><strong>Kontinuit\u00e4t des Verfahrens<\/strong><span> ist der eigentliche Schwerpunkt der neuen Anlage. Das Layout wurde vollst\u00e4ndig nach einem Flussmodell entworfen, das Flexibilit\u00e4t und einen minimalen Einsatz von Personalressourcen erm\u00f6glicht. <\/span><strong>Automatisierung<\/strong><span> bedeutet in diesem Fall nicht nur Effizienz, sondern auch Wiederholbarkeit unter den unterschiedlichsten Arbeitsbedingungen und maximale Reaktionsf\u00e4higkeit auf Marktschwankungen.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Die hier hergestellten <\/span><strong>Rollen<\/strong><span> werden direkt aus geschmiedeten Stahllegierungen gewonnen. Diese werden dann mechanisch bearbeitet, geschwei\u00dft und einer W\u00e4rmebehandlung unterzogen, um die richtigen <\/span><strong>Eigenschaften<\/strong><span> von mechanischer Verschlei\u00dffestigkeit und Best\u00e4ndigkeit zu erhalten.<\/p>\n<p><\/span><\/p>\n<p dir=\"ltr\"><span>Alle Rollen werden <\/span><strong>zu 100 % direkt in der Fertigungsstra\u00dfe getestet<\/strong><span>, mit maximaler Sensibilit\u00e4t f\u00fcr kleineste Abweichungen vom Standard. Nach der Verarbeitung und Pr\u00fcfung sind die bei <\/span><span>ITR Industries Korea<\/span><span> hergestellte Produkte bereit f\u00fcr die Versendung an die verschiedenen ITR-Niederlassungen auf der ganzen Welt und damit direkt an die Endkunden.<br \/><\/span><\/p>\n<p dir=\"ltr\"><span>&nbsp;<\/span><\/p>\n<p><span id=\"docs-internal-guid-a97f31e3-7fff-638a-418c-03ba8410d2f5\"><br \/><img loading=\"lazy\" decoding=\"async\" class=\"leftAlone\" title=\"\" src=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/ITR-Industries-Roller-production.jpg\" alt=\"ITR Industries neuen Rollenfabrik\" width=\"724\" height=\"313\"><\/p>\n<p><\/span><\/p>\n<p>F\u00fcr weitere Informationen \u00fcber die USCO-Unternehmensgruppe und \u00fcber die Produkte des ITR-Sortiments k\u00f6nnen sie uns jederzeit kontaktieren, unsere Mitarbeiter werden auf all Ihre Fragen und Bed\u00fcrfnisse eingehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Herzst\u00fcck der Lieferkette von USCO ITR f\u00fcr den Fahrwerksbau ist ITR Industries mit seinen Niederlassungen in China und S\u00fcdkorea.<\/p>\n","protected":false},"author":1,"featured_media":5028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[118,130],"tags":[],"class_list":["post-4659","post","type-post","status-publish","format-standard","has-post-thumbnail","category-magazin","category-unternehmen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ITR Industries Korea, im Herzen der Lieferkette von USCO ITR - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"Das Herzst\u00fcck der Lieferkette von USCO ITR f\u00fcr den Fahrwerksbau ist ITR Industries mit seinen Niederlassungen in China und S\u00fcdkorea.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T10:26:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Attrezzature-idrauliche-Usco-ITR-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"assistenza@intersezione.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"assistenza@intersezione.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/\"},\"author\":{\"name\":\"assistenza@intersezione.com\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"headline\":\"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR\",\"datePublished\":\"2022-02-03T00:00:00+00:00\",\"dateModified\":\"2026-09-01T10:26:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/\"},\"wordCount\":872,\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Attrezzature-idrauliche-Usco-ITR-cover.jpg\",\"articleSection\":[\"Magazin\",\"Unternehmen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/\",\"name\":\"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Attrezzature-idrauliche-Usco-ITR-cover.jpg\",\"datePublished\":\"2022-02-03T00:00:00+00:00\",\"dateModified\":\"2026-09-01T10:26:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Attrezzature-idrauliche-Usco-ITR-cover.jpg\",\"contentUrl\":\"https:\\\/\\\/itrworld.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Attrezzature-idrauliche-Usco-ITR-cover.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#\\\/schema\\\/person\\\/6bb5bb090af044b166af74630ea6db66\",\"name\":\"assistenza@intersezione.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g\",\"caption\":\"assistenza@intersezione.com\"},\"sameAs\":[\"http:\\\/\\\/itrworld.com\"],\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/author\\\/assistenzaintersezione-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/","og_locale":"de_DE","og_type":"article","og_title":"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR - ITR WORLD","og_description":"Das Herzst\u00fcck der Lieferkette von USCO ITR f\u00fcr den Fahrwerksbau ist ITR Industries mit seinen Niederlassungen in China und S\u00fcdkorea.","og_url":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_published_time":"2022-02-03T00:00:00+00:00","article_modified_time":"2026-09-01T10:26:11+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Attrezzature-idrauliche-Usco-ITR-cover.jpg","type":"image\/jpeg"}],"author":"assistenza@intersezione.com","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"assistenza@intersezione.com","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#article","isPartOf":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/"},"author":{"name":"assistenza@intersezione.com","@id":"https:\/\/itrworld.com\/de\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"headline":"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR","datePublished":"2022-02-03T00:00:00+00:00","dateModified":"2026-09-01T10:26:11+00:00","mainEntityOfPage":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/"},"wordCount":872,"image":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Attrezzature-idrauliche-Usco-ITR-cover.jpg","articleSection":["Magazin","Unternehmen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/","url":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/","name":"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#primaryimage"},"image":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#primaryimage"},"thumbnailUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Attrezzature-idrauliche-Usco-ITR-cover.jpg","datePublished":"2022-02-03T00:00:00+00:00","dateModified":"2026-09-01T10:26:11+00:00","author":{"@id":"https:\/\/itrworld.com\/de\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66"},"breadcrumb":{"@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#primaryimage","url":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Attrezzature-idrauliche-Usco-ITR-cover.jpg","contentUrl":"https:\/\/itrworld.com\/wp-content\/uploads\/2026\/01\/Attrezzature-idrauliche-Usco-ITR-cover.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/de\/itr-industries-korea-im-herzen-der-lieferkette-von-usco-itr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/de\/"},{"@type":"ListItem","position":2,"name":"ITR Industries Korea, im Herzen der Lieferkette von USCO ITR"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/de\/#website","url":"https:\/\/itrworld.com\/de\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/itrworld.com\/de\/#\/schema\/person\/6bb5bb090af044b166af74630ea6db66","name":"assistenza@intersezione.com","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/173da4fe4c6d5f6816b291c4cd7599f4c8a567709e373ff708e7064877b26a05?s=96&d=mm&r=g","caption":"assistenza@intersezione.com"},"sameAs":["http:\/\/itrworld.com"],"url":"https:\/\/itrworld.com\/de\/author\/assistenzaintersezione-com\/"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts\/4659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/comments?post=4659"}],"version-history":[{"count":4,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts\/4659\/revisions"}],"predecessor-version":[{"id":10319,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/posts\/4659\/revisions\/10319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/media\/5028"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/media?parent=4659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/categories?post=4659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/tags?post=4659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}