{"id":9264,"date":"2025-10-10T12:48:08","date_gmt":"2025-10-10T12:48:08","guid":{"rendered":"https:\/\/itrworld.com\/?page_id=9264"},"modified":"2026-07-31T10:50:05","modified_gmt":"2026-07-31T10:50:05","slug":"vision-leitbild-und-werte","status":"publish","type":"page","link":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/","title":{"rendered":"Vision, Leitbild und Werte"},"content":{"rendered":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#0A0000&#8243; bg_image=&#8220;1703&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;275&#8243; left_padding_desktop=&#8220;25px&#8220; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; shape_divider_color=&#8220;#164901&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100px&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;advanced&#8220; shape_type=&#8220;mountains&#8220; advanced_gradient_display_type=&#8220;linear&#8220; height_desktop=&#8220;500px&#8220; height_tablet=&#8220;600&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][nectar_highlighted_text scribble_color=&#8220;#DC0813&#8243; style=&#8220;scribble&#8220; scribble_shape=&#8220;basic-underline&#8220; scribble_thickness=&#8220;regular&#8220; scribble_speed=&#8220;0s&#8220; scribble_easing=&#8220;ease_in_out&#8220; disable_mobile_animation=&#8220;true&#8220; custom_font_size=&#8220;4vw&#8220; font_size_tablet=&#8220;7vw&#8220; font_line_height=&#8220;1.1em&#8220; text_direction=&#8220;default&#8220;]\n<h1><em>Vision, Leitbild und Werte<\/em><\/h1>\n[\/nectar_highlighted_text][vc_custom_heading text=&#8220;Vertrauen schaffen durch Innovation, Qualit\u00e4t und menschenorientierte L\u00f6sungen \u2013 f\u00fcr nachhaltigen Mehrwert.&#8220; font_container=&#8220;tag:p|font_size:28px|text_align:left|color:%23FFFFFF&#8220; use_theme_fonts=&#8220;yes&#8220; css_animation=&#8220;fadeIn&#8220; css=&#8220;&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#E4E4E4&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;80px&#8220; bottom_padding=&#8220;50px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column constrain_group_100=&#8220;yes&#8220; constrain_group_101=&#8220;yes&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Vision<\/h2>\n<p>Stellen wir uns eine Branche vor, in der Zuverl\u00e4ssigkeit, Innovation und Kompetenz nicht nur Versprechen, sondern Gewissheiten sind. Unser Ziel ist klar: Wir wollen weiterhin ein solider und anerkannter Bezugspunkt in der Welt der Ersatzteile und Ausr\u00fcstungen f\u00fcr Erdbewegungsmaschinen sein und zu einer Zukunft beitragen, in der jedes Bauteil einen greifbaren und dauerhaften Wert hat, der auf Vertrauen basiert.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1725&#8243; image_size=&#8220;medium&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#F5F5F7&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;80px&#8220; bottom_padding=&#8220;50px&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1720&#8243; image_size=&#8220;medium&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column][vc_column constrain_group_100=&#8220;yes&#8220; constrain_group_101=&#8220;yes&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Leitbild<\/h2>\n<p>Wir setzen uns jeden Tag daf\u00fcr ein, dass unsere Arbeit f\u00fcr sich selbst spricht. Wir liefern Ersatzteile und Ausr\u00fcstung, die auf Langlebigkeit ausgelegt sind, eine hohe Leistung bieten und eine echte Rendite gew\u00e4hrleisten. Doch damit nicht genug: Wir haben ein offenes Ohr f\u00fcr unsere Kunden, begleiten und unterst\u00fctzen sie in jeder Phase und bieten ma\u00dfgeschneiderte L\u00f6sungen sowie eine kontinuierliche und konkrete Betreuung, die genau auf ihre betrieblichen Anforderungen zugeschnitten ist.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#E4E4E4&#8243; scene_position=&#8220;center&#8220; bottom_padding=&#8220;100&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;speech&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1761921886817{padding-top: 50px !important;}&#8220;][vc_column_inner top_padding_desktop=&#8220;0&#8243; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;0&#8243; left_padding_desktop=&#8220;20px&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;20px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#F2F2F2&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#DC0813&#8243; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220; content_layout=&#8220;default&#8220;][image_with_animation image_url=&#8220;1731&#8243; image_size=&#8220;medium&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8220;0&#8243; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;0&#8243; left_padding_desktop=&#8220;20px&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;20px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#F2F2F2&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#DC0813&#8243; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220; content_layout=&#8220;default&#8220;][image_with_animation image_url=&#8220;1738&#8243; image_size=&#8220;medium&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8220;0&#8243; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;0&#8243; left_padding_desktop=&#8220;20px&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;20px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#F2F2F2&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#DC0813&#8243; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220; content_layout=&#8220;default&#8220;][image_with_animation image_url=&#8220;1770&#8243; image_size=&#8220;medium&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8220;yes&#8220; column_margin=&#8220;20px&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220; css=&#8220;.vc_custom_1761921886817{padding-top: 50px !important;}&#8220;][vc_column_inner top_padding_desktop=&#8220;0&#8243; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;0&#8243; left_padding_desktop=&#8220;20px&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;20px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#0A0000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#DC0813&#8243; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220; content_layout=&#8220;default&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Das Herzst\u00fcck unserer T\u00e4tigkeit<\/h2>\n<p>Das Produkt steht im Mittelpunkt jeder unserer Entscheidungen. Es ist das Ergebnis von Forschung, Erfahrung und Marktkenntnis. Wir investieren in Innovation und in die Erweiterung unseres Sortiments mit einem klaren Ziel: Komponenten zu entwickeln, die nicht nur funktional, sondern auch f\u00fcr ihre Qualit\u00e4t, Einzigartigkeit und Individualit\u00e4t bekannt sind.[\/vc_column_text][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8220;0&#8243; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;0&#8243; left_padding_desktop=&#8220;20px&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;20px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#0A0000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#DC0813&#8243; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220; content_layout=&#8220;default&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Von Menschen getragen<\/h2>\n<p>Hinter jedem Erfolg steht ein eingespieltes, vielf\u00e4ltiges und motiviertes Team. Wir glauben an den Wert der Menschen und an die Kraft der Zusammenarbeit. Wir sch\u00e4tzen Kompetenzen, Kulturen und Talente als wertvolle Ressourcen. Wir f\u00f6rdern ein Umfeld, das auf gegenseitigem Vertrauen, Respekt und Integrit\u00e4t basiert: einen Ort, an dem jeder einen Beitrag leisten, sich weiterentwickeln und etwas bewirken kann.[\/vc_column_text][\/vc_column_inner][vc_column_inner top_padding_desktop=&#8220;0&#8243; constrain_group_100=&#8220;yes&#8220; bottom_padding_desktop=&#8220;0&#8243; left_padding_desktop=&#8220;20px&#8220; constrain_group_101=&#8220;yes&#8220; right_padding_desktop=&#8220;20px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; font_color=&#8220;#0A0000&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;20px&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_color=&#8220;#DC0813&#8243; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220; content_layout=&#8220;default&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2>Leidenschaft f\u00fcr das, was wir tun<\/h2>\n<p>Unsere Neugier treibt uns dazu an, neue L\u00f6sungen zu erkunden, und unsere Leidenschaft spornt uns dazu an, unser Bestes zu geben. Wir arbeiten mit Begeisterung daran, jedes Detail zum Teil eines Systems zu machen, das funktioniert, w\u00e4chst und sich weiterentwickelt.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#0A0000&#8243; bg_image=&#8220;1703&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;275&#8243; left_padding_desktop=&#8220;25px&#8220; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; shape_divider_color=&#8220;#164901&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100px&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;advanced&#8220; shape_type=&#8220;mountains&#8220; advanced_gradient_display_type=&#8220;linear&#8220; height_desktop=&#8220;500px&#8220; height_tablet=&#8220;600&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8223,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"page_category":[],"page_tag":[],"class_list":["post-9264","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vision, Leitbild und Werte - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vision, Leitbild und Werte - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#0A0000&#8243; bg_image=&#8220;1703&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;275&#8243; left_padding_desktop=&#8220;25px&#8220; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; shape_divider_color=&#8220;#164901&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100px&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;advanced&#8220; shape_type=&#8220;mountains&#8220; advanced_gradient_display_type=&#8220;linear&#8220; height_desktop=&#8220;500px&#8220; height_tablet=&#8220;600&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-31T10:50:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/die-unternehmensgruppe\\\/vision-leitbild-und-werte\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/die-unternehmensgruppe\\\/vision-leitbild-und-werte\\\/\",\"name\":\"Vision, Leitbild und Werte - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\"},\"datePublished\":\"2025-10-10T12:48:08+00:00\",\"dateModified\":\"2026-07-31T10:50:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/die-unternehmensgruppe\\\/vision-leitbild-und-werte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/de\\\/die-unternehmensgruppe\\\/vision-leitbild-und-werte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/die-unternehmensgruppe\\\/vision-leitbild-und-werte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die unternehmensgruppe\",\"item\":\"https:\\\/\\\/itrworld.com\\\/de\\\/die-unternehmensgruppe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vision, Leitbild und Werte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vision, Leitbild und Werte - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/","og_locale":"de_DE","og_type":"article","og_title":"Vision, Leitbild und Werte - ITR WORLD","og_description":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#0A0000&#8243; bg_image=&#8220;1703&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right center&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;275&#8243; left_padding_desktop=&#8220;25px&#8220; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; shape_divider_color=&#8220;#164901&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100px&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;advanced&#8220; shape_type=&#8220;mountains&#8220; advanced_gradient_display_type=&#8220;linear&#8220; height_desktop=&#8220;500px&#8220; height_tablet=&#8220;600&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243;...","og_url":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_modified_time":"2026-07-31T10:50:05+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/","url":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/","name":"Vision, Leitbild und Werte - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/de\/#website"},"datePublished":"2025-10-10T12:48:08+00:00","dateModified":"2026-07-31T10:50:05+00:00","breadcrumb":{"@id":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/vision-leitbild-und-werte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/de\/"},{"@type":"ListItem","position":2,"name":"Die unternehmensgruppe","item":"https:\/\/itrworld.com\/de\/die-unternehmensgruppe\/"},{"@type":"ListItem","position":3,"name":"Vision, Leitbild und Werte"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/de\/#website","url":"https:\/\/itrworld.com\/de\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/9264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/comments?post=9264"}],"version-history":[{"count":4,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/9264\/revisions"}],"predecessor-version":[{"id":9280,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/9264\/revisions\/9280"}],"up":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/8223"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/media?parent=9264"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/page_category?post=9264"},{"taxonomy":"page_tag","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/page_tag?post=9264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}