{"id":8295,"date":"2025-10-10T12:50:23","date_gmt":"2025-10-10T12:50:23","guid":{"rendered":"https:\/\/itrworld.com\/?page_id=8295"},"modified":"2026-06-24T16:23:22","modified_gmt":"2026-06-24T16:23:22","slug":"recycling","status":"publish","type":"page","link":"https:\/\/itrworld.com\/de\/branchen\/recycling\/","title":{"rendered":"Recycling"},"content":{"rendered":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#E5E5E5&#8243; bg_image=&#8220;5544&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;300&#8243; left_padding_desktop=&#8220;25px&#8220; top_padding_tablet=&#8220;250&#8243; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#0A000036&#8243; color_overlay_2=&#8220;#000000&#8243; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220; min_height_desktop=&#8220;500&#8243; min_height_tablet=&#8220;350&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner left_padding_desktop=&#8220;50px&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;advanced&#8220; gradient_type=&#8220;default&#8220;][nectar_highlighted_text scribble_color=&#8220;#DC0813&#8243; style=&#8220;scribble&#8220; scribble_shape=&#8220;basic-underline&#8220; scribble_thickness=&#8220;regular&#8220; scribble_speed=&#8220;0s&#8220; scribble_easing=&#8220;ease_in_out&#8220; disable_mobile_animation=&#8220;true&#8220; custom_font_size=&#8220;4vw&#8220; font_size_tablet=&#8220;7vw&#8220; font_line_height=&#8220;1.1em&#8220; text_direction=&#8220;default&#8220;]\n<h1><em>Recycling<\/em><\/h1>\n[\/nectar_highlighted_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;right&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; column_padding_type=&#8220;default&#8220; gradient_type=&#8220;default&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;25px&#8220; bottom_margin=&#8220;50&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;2\/3&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]Im Recyclingbereich liefert die ITR-Gruppe spezialisierte Komponenten f\u00fcr Maschinen, die in der Zerkleinerung, Sortierung und im Materialumschlag eingesetzt werden, sowie hydraulische Anbauger\u00e4te wie Greifer, Brecher und Scheren.<\/p>\n<p>Unsere Produkte sind so ausgelegt, dass sie auch unter rauen Einsatzbedingungen und bei dauerhafter mechanischer Beanspruchung eine zuverl\u00e4ssige Leistung und lange Lebensdauer gew\u00e4hrleisten.<\/p>\n<p>Durch die Steigerung der betrieblichen Effizienz und die Reduzierung von Ausfallzeiten unterst\u00fctzen wir die Kreislaufwirtschaft und sorgen f\u00fcr einen kontinuierlichen und sicheren Betrieb von Maschinen in Recyclinganlagen.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#E5E5E5&#8243; bg_image=&#8220;5544&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;300&#8243; left_padding_desktop=&#8220;25px&#8220; top_padding_tablet=&#8220;250&#8243; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#0A000036&#8243; color_overlay_2=&#8220;#000000&#8243; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220; min_height_desktop=&#8220;500&#8243; min_height_tablet=&#8220;350&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":8273,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"page_category":[],"page_tag":[],"class_list":["post-8295","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recycling - ITR WORLD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itrworld.com\/de\/branchen\/recycling\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recycling - ITR WORLD\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#E5E5E5&#8243; bg_image=&#8220;5544&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;300&#8243; left_padding_desktop=&#8220;25px&#8220; top_padding_tablet=&#8220;250&#8243; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#0A000036&#8243; color_overlay_2=&#8220;#000000&#8243; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220; min_height_desktop=&#8220;500&#8243; min_height_tablet=&#8220;350&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itrworld.com\/de\/branchen\/recycling\/\" \/>\n<meta property=\"og:site_name\" content=\"ITR WORLD\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uscoitr\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T16:23:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/branchen\\\/recycling\\\/\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/branchen\\\/recycling\\\/\",\"name\":\"Recycling - ITR WORLD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\"},\"datePublished\":\"2025-10-10T12:50:23+00:00\",\"dateModified\":\"2026-06-24T16:23:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/branchen\\\/recycling\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/itrworld.com\\\/de\\\/branchen\\\/recycling\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/branchen\\\/recycling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Branchen\",\"item\":\"https:\\\/\\\/itrworld.com\\\/de\\\/branchen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recycling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itrworld.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/itrworld.com\\\/de\\\/\",\"name\":\"ITR WORLD\",\"description\":\"Spare and repair parts excavators &amp; mini diggers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itrworld.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recycling - ITR WORLD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itrworld.com\/de\/branchen\/recycling\/","og_locale":"de_DE","og_type":"article","og_title":"Recycling - ITR WORLD","og_description":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;bottom&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#E5E5E5&#8243; bg_image=&#8220;5544&#8243; bg_image_type=&#8220;default&#8220; bg_position=&#8220;right bottom&#8220; background_image_loading=&#8220;default&#8220; bg_repeat=&#8220;no-repeat&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;300&#8243; left_padding_desktop=&#8220;25px&#8220; top_padding_tablet=&#8220;250&#8243; left_padding_tablet=&#8220;2%&#8220; constrain_group_4=&#8220;yes&#8220; right_padding_tablet=&#8220;2%&#8220; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; row_position_desktop=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; class=&#8220;force_gradient&#8220; enable_gradient=&#8220;true&#8220; color_overlay=&#8220;#0A000036&#8243; color_overlay_2=&#8220;#000000&#8243; overlay_strength=&#8220;0.95&#8243; gradient_direction=&#8220;top_to_bottom&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220; min_height_desktop=&#8220;500&#8243; min_height_tablet=&#8220;350&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; flex_gap_desktop=&#8220;10px&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220;...","og_url":"https:\/\/itrworld.com\/de\/branchen\/recycling\/","og_site_name":"ITR WORLD","article_publisher":"https:\/\/www.facebook.com\/uscoitr","article_modified_time":"2026-06-24T16:23:22+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/itrworld.com\/wp-content\/uploads\/2025\/10\/usco-itr-facciata.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/itrworld.com\/de\/branchen\/recycling\/","url":"https:\/\/itrworld.com\/de\/branchen\/recycling\/","name":"Recycling - ITR WORLD","isPartOf":{"@id":"https:\/\/itrworld.com\/de\/#website"},"datePublished":"2025-10-10T12:50:23+00:00","dateModified":"2026-06-24T16:23:22+00:00","breadcrumb":{"@id":"https:\/\/itrworld.com\/de\/branchen\/recycling\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/itrworld.com\/de\/branchen\/recycling\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/itrworld.com\/de\/branchen\/recycling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itrworld.com\/de\/"},{"@type":"ListItem","position":2,"name":"Branchen","item":"https:\/\/itrworld.com\/de\/branchen\/"},{"@type":"ListItem","position":3,"name":"Recycling"}]},{"@type":"WebSite","@id":"https:\/\/itrworld.com\/de\/#website","url":"https:\/\/itrworld.com\/de\/","name":"ITR WORLD","description":"Spare and repair parts excavators &amp; mini diggers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itrworld.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/8295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/comments?post=8295"}],"version-history":[{"count":2,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/8295\/revisions"}],"predecessor-version":[{"id":8303,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/8295\/revisions\/8303"}],"up":[{"embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/pages\/8273"}],"wp:attachment":[{"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/media?parent=8295"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/page_category?post=8295"},{"taxonomy":"page_tag","embeddable":true,"href":"https:\/\/itrworld.com\/de\/wp-json\/wp\/v2\/page_tag?post=8295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}